{"id":29822,"date":"2016-02-21T16:03:13","date_gmt":"2016-02-21T14:03:13","guid":{"rendered":"https:\/\/stg.beecare.ch\/una-prospettiva-diversa\/"},"modified":"2023-05-08T16:01:07","modified_gmt":"2023-05-08T14:01:07","slug":"eine-andere-perspektive","status":"publish","type":"post","link":"https:\/\/stg.beecare.ch\/de\/news\/eine-andere-perspektive\/","title":{"rendered":"Eine andere Perspektive"},"content":{"rendered":"<br \/>\n<blockquote>\n<h4>\u201e<em>Die Zeit, die du f\u00fcr deine Rose verloren hast, macht deine Rose so wichtig.<\/em>\u201c<br \/>-Antoine de Saint Exup\u00e9ry-<\/h4>\n<\/blockquote>\n<p>F\u00fcr unser Personal ist ein getanes Werk nicht nur ein einfache T\u00e4tigkeit, sondern viel mehr \u2013 sie hat einen Sinn f\u00fcr denjenigen, der das Werk vollbringt, und auch f\u00fcr denjenigen, f\u00fcr den sie gedacht ist. Hinter jeder T\u00e4tigkeit steckt eine ganz bestimmte Absicht und daher Engagement. Die Person, der eine T\u00e4tigkeit gewidmet ist, erh\u00e4lt damit nicht nur eine Leistung entsprechend ihrer Bed\u00fcrfnisse, sondern nimmt auch wahr, dass sie damit in ihrer W\u00fcrde und als Person geachtet ist.<\/p>\n<p>Und die dazugeh\u00f6rigen Gesten im Alltag sagen mehr aus als es Worte je k\u00f6nnten. Das Streicheln einer Hand, eine auf die bed\u00fcrftige Person zugeschnittene Handlung, ein Blick oder ein unerwarteter Gru\u00df \u2013 solche Gesten vertreiben \u00c4ngste und erinnern uns daran, was es bedeutet, ein Mensch zu sein.<\/p>\n<blockquote>\n<h4><em>\u201eWas dem ganzen Bienenschwarm nicht zutr\u00e4glich ist, das ist auch der Biene nicht zutr\u00e4glich.\u201c<\/em><br \/>-Marc Aurel-<\/h4>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr unser Personal ist ein getanes Werk nicht nur ein einfache T\u00e4tigkeit, sondern viel mehr \u2013 sie hat einen Sinn f\u00fcr denjenigen, der das Werk vollbringt, und auch f\u00fcr denjenigen, f\u00fcr den sie gedacht ist. Hinter jeder T\u00e4tigkeit steckt eine ganz bestimmte Absicht und daher Engagement. <\/p>\n","protected":false},"author":1,"featured_media":238257,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-29822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/29822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=29822"}],"version-history":[{"count":0,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/29822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media\/238257"}],"wp:attachment":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=29822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/categories?post=29822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/tags?post=29822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}