{"id":246845,"date":"2024-03-20T09:44:09","date_gmt":"2024-03-20T07:44:09","guid":{"rendered":"https:\/\/stg.beecare.ch\/?p=246845"},"modified":"2024-08-07T09:50:32","modified_gmt":"2024-08-07T07:50:32","slug":"der-kantonale-beitrag-fur-den-verbleib-zuhause","status":"publish","type":"post","link":"https:\/\/stg.beecare.ch\/de\/news\/der-kantonale-beitrag-fur-den-verbleib-zuhause\/","title":{"rendered":"Der kantonale Beitrag f\u00fcr den Verbleib zuhause"},"content":{"rendered":"<p><strong>BeeCare<\/strong> unterst\u00fctzt bis heute mehr als 370 Familien, die aus verschiedenen Gr\u00fcnden um Unterst\u00fctzung bei der Pflege ihrer \u00e4lteren, kranken oder verletzten Familienmitglieder gebeten haben<\/p>\n<p>Wir haben deshalb <strong>Gabriele Fattorini<\/strong>, Direktor der <em>Abteilung f\u00fcr Soziales und Familie (DASF)<\/em> des Kantons Tessin, gebeten, uns die <strong>Kantonale Direkthilfe f\u00fcr die Pflege zuhause n\u00e4her zu erl\u00e4utern.<\/strong><\/p>\n<p><strong>Wie funktioniert der kantonale Beitrag an die Pflege f\u00fcr den Verbleib zuhause?<\/strong><br \/>\n\u201e<em>Die Direkthilfe (AD) ist im Pflegegesetz <a title=\"h\u00e4usliche Pflege und Betreuung im Kanton Tessin\" href=\"https:\/\/stg.beecare.ch\/assistenza-domiciliare\/\">Heimpflege<\/a> (LACD) vorgesehen. Sie dient der finanziellen Unterst\u00fctzung von \u00e4lteren oder behinderten Personen, die eine AHV- oder IV-Rente beziehen und aufgrund ihrer Pflegebed\u00fcrftigkeit auf die Hilfe anderer Personen (Familienangeh\u00f6rige oder Dritte) angewiesen sind, um zuhause bleiben zu k\u00f6nnen und so einen Eintritt in ein Pflegeheim zu vermeiden. Es handelt sich um eine Form der finanziellen Unterst\u00fctzung, die seit dem 1. Januar 1993 in Kraft ist und anderen Interventionen und Regelungen wie der Schwerbehindertenzulage (AGI) untergeordnet ist. Die Direkthilfe (AD) wird aufgrund der finanziellen Situation des Antragstellers gew\u00e4hrt und auf der Grundlage des Entscheids \u00fcber die Gew\u00e4hrung einer AHV\/IV-Erg\u00e4nzungsleistung (EL) oder, falls diese nicht gew\u00e4hrt wird, auf der Grundlage der entsprechenden Berechnungstabelle berechnet.<\/em><br \/>\n<em><br \/>\nZus\u00e4tzlich zu dieser Form der <strong>Finanzhilfe f\u00fcr die <a title=\"Hilfe beim Verbleib zuhause\" href=\"https:\/\/stg.beecare.ch\/assistenza-domiciliare\/\">mantenimento a domicilio<\/a><\/strong> sieht das LACD (kantonales Assistenz und Heimpflegegesetz) auch einen Beitrag f\u00fcr die Organisation individueller Wohnformen vor. Damit werden \u00e4ltere oder behinderte Personen, welche erhebliche Kosten aufwenden m\u00fcssen, finanziell unterst\u00fctzt um ihre Wohnung so anzupassen, damit sie dort weiterhin wohnen k\u00f6nnen; zum Beispiel durch die Beseitigung baulicher Barrieren.<\/em>&#187;<\/p>\n<p><strong>Wie unterscheidet sich diese Direkthilfe von der AGI-F\u00f6rderung oder den PC-Beitr\u00e4gen der AHV?<\/strong><br \/>\n\u201e<em>Die Direkthilfe richtet sich nach der finanziellen Leistungsf\u00e4higkeit und dem Grad der Pflegebed\u00fcrftigkeit des Antragstellers und ist subsidi\u00e4r zu anderen Leistungen, die f\u00fcr den gleichen Zweck gew\u00e4hrt werden, wie z.B. die AHV\/IV-Erg\u00e4nzungsleistungen und das Bundesgesetz des Versicherungsvertrages (VVG).<\/em>&#187;<\/p>\n<p><strong>Wie kann die subventionierte Person diese finanzielle Unterst\u00fctzung f\u00fcr den Verbleib zuhause verwenden? <\/strong><br \/>\n\u201e<em>Die Direkthilfe wird f\u00fcr die Bezahlung einer oder mehrerer Betreuungspersonen gew\u00e4hrt. In den meisten F\u00e4llen handelt es sich dabei um T\u00f6chter oder S\u00f6hne \u00e4lterer Menschen, die wegen der Pflege ihrer Angeh\u00f6rigen ihre Arbeit aufgegeben haben. Dies geht aus einer Studie der SUPSI hervor, die 2019 im Auftrag des DSS einen <a title=\"Evaluierungsbericht \u00fcber die Direkthilfe\" href=\"https:\/\/www4.ti.ch\/fileadmin\/DSS\/DASF\/UACD\/Pianificazione\/Allegato11_Valutazione_aiuti_diretti_SUPSI.pdf\" target=\"_blank\" rel=\"noopener\">Evaluierungsbericht \u00fcber die Direkthilfe<\/a> vorgelegt hat; dieser Verzicht wird insbesondere von den M\u00fcttern von behinderten Leistungsempf\u00e4ngern (4 von 5) und den T\u00f6chtern von \u00e4lteren Leistungsempf\u00e4ngern (1 von 3) geleistet. In diesen F\u00e4llen stellt der Beitrag ein zus\u00e4tzliches Einkommen im Familienhaushalt dar. Aus diesem Grund werden Personen, die Direkthilfen erhalten, dem Sozialversicherungsinstitut systematisch als Arbeitgeber gemeldet.<\/em><\/p>\n<p><em>Wenn jedoch nachgewiesen werden kann, dass die Direkthilfe zur Bezahlung der hauswirtschaftlichen Dienstleistungen eines <strong>h\u00e4uslichen Pflegedienstes<\/strong> verwendet wird und der Beitrag tats\u00e4chlich nicht an Dritte weitergegeben wird, erlischt die Zugeh\u00f6rigkeit als Arbeitgeber. In diesen besonderen F\u00e4llen ist jedoch zu ber\u00fccksichtigen, dass der Leistungsempf\u00e4nger, bei dem es sich oft um eine \u00e4ltere Person handelt, die f\u00fcr den gleichen Zweck gew\u00e4hrten R\u00fcckerstattungen, auf die sie Anspruch hat, beantragen muss und dass diese dann vom Beitrag abgezogen werden (z.B. R\u00fcckerstattung f\u00fcr den Haushaltsunterhalt oder R\u00fcckerstattung f\u00fcr die Kosten der h\u00e4uslichen Pflege der AHV\/IV oder des KLV (Krankenpflege-Leistungsverordnung). Zudem unterliegt die Subvention f\u00fcr die h\u00e4usliche Pflege der Besteuerung; sie gilt daher als steuerbares Einkommen f\u00fcr den Leistungsempf\u00e4nger selbst oder f\u00fcr die Personen, denen sie in Form von Lohn f\u00fcr die geleistete Pflege ausgezahlt wird.<\/em>&#187;<\/p>\n<p><strong>Warum hat sich unser Kanton f\u00fcr die Unterst\u00fctzung der h\u00e4uslichen Pflege entschieden? Diese Subvention wird im Vergleich zur \u00fcbrigen Schweiz fast ausschlie\u00dflich im Tessin angeboten.<\/strong><br \/>\n\u201e<em>Die Ausrichtung auf die Pflege zuhause wird im Tessin seit etwa zwei Jahrzehnten durch den Grundsatz \u201eambulant vor station\u00e4r\u201c bekr\u00e4ftigt, wobei man (zusammen mit anderen Kantonen, vor allem in der Westschweiz) die von der <strong>Konferenz der kantonalen Gesundheitsdirektoren (CDS)<\/strong> eingeschlagene Richtung vorweggenommen hat und ihr dann folgte. Diese Strategie manifestiert sich einerseits in der schrittweisen Reduktion der Bettenzahl in den medizinischen Einrichtungen im Verh\u00e4ltnis zur \u00fcber 80-j\u00e4hrigen Bev\u00f6lkerung und andererseits in der starken Ausrichtung auf die h\u00e4usliche Pflege und Betreuung zu Hause, sowie auf Dienstleistungen und Unterst\u00fctzungsangebote zum Verbleib der \u00e4lteren Menschen zu Hause.<\/em><\/p>\n<p><em>Die Integrierte LAnz-LACD-Planung 2021-2030 bekr\u00e4ftigt ebenfalls den Grundsatz der Bevorzugung der h\u00e4uslichen Pflege und versucht, diesen durch die Unterst\u00fctzung einer Reihe von Diensten und Leistungen weiter zu st\u00e4rken, die die M\u00f6glichkeit des Verbleibs zu Hause unter Ber\u00fccksichtigung der W\u00fcnsche der Bed\u00fcrftigen und ihrer Familien gew\u00e4hrleisten&#187;.<\/em><\/p>\n<p><strong>Gibt es weitere finanzielle Unterst\u00fctzungen, die der Kanton \u00e4lteren Menschen gew\u00e4hrt, um Dienstleistungen au\u00dferhalb des Gesundheitswesens zu verg\u00fcten? <\/strong><br \/>\n<em>\u201eDer Kanton finanziert im Auftrag des Bundes die Erg\u00e4nzungsleistungen, die eine Reihe von finanziellen Hilfen zur Deckung der Kosten von Krankheit und Behinderung garantieren, wie auch die R\u00fcckerstattung der Kosten der Haushaltshilfe, Pflege und Betreuung sowie der Transportkosten. Dar\u00fcber hinaus finanziert der Kanton die Unterst\u00fctzungsleistungen des Gesetzes \u00fcber die h\u00e4usliche Pflege und Betreuung, die eine Reihe von Dienstleistungen f\u00fcr Menschen garantieren, die aufgrund von Krankheit, Unfall, Behinderung, Mutterschaft, Alter oder sozial-famili\u00e4ren Schwierigkeiten Hilfe zu Hause ben\u00f6tigen. Dazu geh\u00f6ren insbesondere Tagesst\u00e4tten mit sozialer Betreuung (CDSA), therapeutische Tagesst\u00e4tten, Transportdienste und Mahlzeiten zu Hause\u201c,<\/em> fasst <strong>Gabriele Fattorini<\/strong> zusammen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie, wie die Direkthilfen des Kantons Tessin \u00e4ltere und behinderte Menschen zu Hause unterst\u00fctzen, indem sie finanzielle L\u00f6sungen und famili\u00e4res Wohlergehen anbieten.<\/p>\n","protected":false},"author":1,"featured_media":238306,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-246845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/246845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=246845"}],"version-history":[{"count":0,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/246845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media\/238306"}],"wp:attachment":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=246845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/categories?post=246845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/tags?post=246845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}