{"id":246809,"date":"2021-09-14T15:12:00","date_gmt":"2021-09-14T13:12:00","guid":{"rendered":"https:\/\/stg.beecare.ch\/?p=246809"},"modified":"2024-08-06T10:37:38","modified_gmt":"2024-08-06T08:37:38","slug":"von-der-italienischen-schweiz-nach-venezuela-das-know-how-der-heimpflege-reist-mit-beecare-und-trabajo-y-persona-uber-den-ozean","status":"publish","type":"post","link":"https:\/\/stg.beecare.ch\/de\/news\/von-der-italienischen-schweiz-nach-venezuela-das-know-how-der-heimpflege-reist-mit-beecare-und-trabajo-y-persona-uber-den-ozean\/","title":{"rendered":"Von der italienischen Schweiz nach Venezuela: Das Know-how der Heimpflege reist mit BeeCare und Trabajo y Persona \u00fcber den Ozean"},"content":{"rendered":"<p><em>Die Tessiner Spitex nimmt die Herausforderung der internationalen Ausbildung an und hat dank der Begegnung mit Trabajo y Persona, einem venezolanischen Verband, der sich mit Ausbildung und Arbeit befasst, im Sommer 2021 eine Reihe von Workshops und Fernausbildungssitzungen f\u00fcr Assistentinnen und Assistenten der Heimpflege in Venezuela er\u00f6ffnet.<\/em><\/p>\n<p>Lugano, August 2021 &#8211; Die Aufmerksamkeit f\u00fcr die Person in all ihren Aspekten ist eines der Grundprinzipien, auf denen <strong>BeeCare<\/strong> seine Arbeit aufbaut. Ein Treffen mit dem Gr\u00fcnder von <strong>Trabajo Y Persona<\/strong>, <strong>Alejandro Marius<\/strong>, f\u00fchrte zu einer sofortigen Verbindung, die sich auch dank der neuen Technologien zu einer Zusammenarbeit entwickelt hat. <strong>Trabajo Y Persona<\/strong> ist ein 2009 in <strong>Caracas gegr\u00fcndeter Verein<\/strong>, der sich zum Ziel gesetzt hat, den Wert der Arbeit und die W\u00fcrde der Person in der venezolanischen Gesellschaft zu f\u00f6rdern. Zu seinen Projekten geh\u00f6rt ein Berufskurs f\u00fcr h\u00e4usliche Pflegeassistenten, f\u00fcr welchen <strong>BeeCare<\/strong> einen Ad-hoc-Schulungskurs entwickelt hat, in dem Workshops und Videos mit zoom durchgef\u00fchrt werden, die die Arbeitsmethode der Schweizer <strong>Spitex<\/strong> veranschaulichen.<\/p>\n<p>Auf einen Blick die Punkte des ersten internationalen Schulungsworkshops, von <strong>Luca Milesi<\/strong>, Leiter der h\u00e4uslichen Pflege bei <strong>BeeCare<\/strong>, der die Arbeitsweise der <strong>Tessiner <strong>Spitex<\/strong> beschrieben hat.<\/strong><\/p>\n<ul>\n<li>BeeCare ist eine Spitex, die aus der direkten Erfahrung mit der h\u00e4uslichen Pflege eines Familienmitglieds, einiger ihrer Gr\u00fcnder und Mitarbeiter, entstanden ist. BeeCare wurde als Antwort auf ein Bed\u00fcrfnis geboren und wir haben die Arbeit der h\u00e4uslichen Pflege durch die Begegnung mit den Familien entwickelt.<\/li>\n<li>Unsere Arbeitsweise geht auf die Vision zur\u00fcck, was es bedeutet, f\u00fcr jemanden zu sorgen. F\u00fcr BeeCare bedeutet die Pflege eines Menschen in erster Linie, ihn zu lieben. Auch die Mitarbeiter profitieren von dieser Methode, und viele unserer Pflegekr\u00e4fte empfinden gro\u00dfe Freude an ihrer Arbeit. Es ist wichtig, auf die Bed\u00fcrfnisse unserer Mitarbeiter einzugehen, damit sie sich zun\u00e4chst willkommen f\u00fchlen und sich so auf das Leid, welchem sie begegnen, einlassen k\u00f6nnen: der Mitarbeiter pflegt und betreut besser, wenn er selbst gut umsorgt wird.<\/li>\n<li>Wir haben erkannt, dass es notwendig ist sich einf\u00fchlend in die H\u00e4user der Patienten zu begeben um so ein Vertrauensverh\u00e4ltnis aufzubauen, welches die Grundlage f\u00fcr den Aufbau der Arbeit bildet.<\/li>\n<li>Auf organisatorischer Ebene agiert BeeCare als Vermittler, um die Beziehung zwischen Krankenschwestern, h\u00e4uslichen Assistenten und Familien so weit wie m\u00f6glich zu erleichtern. Die direkte Beziehung zwischen Pflegekraft und Familie birgt n\u00e4mlich ein gro\u00dfes Risiko: Die Familie hat Angst, der Pflegekraft mitzuteilen, dass bestimmte Arbeitspunkte verbessert werden m\u00fcssen, weil sie bef\u00fcrchtet, sie zu verlieren. Oder die Pflegekraft akzeptiert neue Bedingungen, weil sie bef\u00fcrchtet, ihren Arbeitsplatz zu verlieren. Wir sind ein ernstzunehmender Gespr\u00e4chspartner f\u00fcr die Familien und begleiten das Personal bei der Aus\u00fcbung seiner Arbeit.<\/li>\n<li>F\u00fcr uns ist es wichtig, den Menschen als Person zu behandeln, ein grundlegender Punkt, der in seiner Einfachheit niemals als selbstverst\u00e4ndlich angesehen wird. Wir verlangen von unseren Betreuern ein w\u00f6chentliches Feedback und bieten ihnen angemessene Schichten an. Bestimmt lassen wir sie nie allein und oft erz\u00e4hlen uns die Mitarbeiter von den dramatischsten Situationen, mit denen sie konfrontiert sind.<\/li>\n<li>Wir legen gro\u00dfen Wert auf die st\u00e4ndige Weiterbildung aller Mitarbeiter, vom F\u00fchren eines Pflegetagebuchs \u00fcber die Lagerung von Lebensmitteln bis hin zu Sprachkursen, um auch nicht italienisch sprechenden Familien helfen zu k\u00f6nnen. Die f\u00fcr diese Art von Arbeit erforderlichen F\u00e4higkeiten sind Einf\u00fchlungsverm\u00f6gen, Fachkenntnisse in der Gesundheitsf\u00fcrsorge und Authentizit\u00e4t der Person. Das Bed\u00fcrfnis zu arbeiten reicht nicht aus, man muss auch ein Interesse an der Pflege der zu betreuenden Person haben.<\/li>\n<li>Eine letzte Bemerkung zur h\u00e4uslichen Pflege w\u00e4hrend der Pandemie: Die Familien waren zun\u00e4chst ver\u00e4ngstigt und wollten keine zus\u00e4tzliche Person zu Hause haben. Aber als sie mit der Unm\u00f6glichkeit konfrontiert wurden, sich alleine um ihren Angeh\u00f6rigen zu k\u00fcmmern, explodierte die Nachfrage nach h\u00e4uslicher Pflege erneut. BeeCare hat alle Ma\u00dfnahmen ergriffen, um einen Schutzplan zu erstellen und alle Hygiene- und Verhaltensvorschriften einzuhalten, um weiterhin sicher arbeiten zu k\u00f6nnen.<\/li>\n<\/ul>\n<p>Die \u00dcberlegungen zu der bei BeeCare angewandten Arbeitsmethode wurden mit allen h\u00e4uslichen Pflegehelfern in der Ausbildung bei <strong>Trabajo Y Persona<\/strong> in Venezuela geteilt, wodurch ein internationaler Dialog \u00fcber ein aktuelles Thema in Gang gesetzt wurde, welches fr\u00fcher oder sp\u00e4ter jeden betrifft: die Pflege eines geliebten Menschen auf die, f\u00fcr alle beteiligten, beste und nachhaltigste Weise.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Tessiner Spitex nimmt die Herausforderung der internationalen Ausbildung an und hat dank der Begegnung mit Trabajo y Persona, einem venezolanischen Verband, der sich mit Ausbildung und Arbeit befasst, im Sommer 2021 eine Reihe von Workshops und Fernausbildungssitzungen f\u00fcr Assistentinnen und Assistenten der Heimpflege in Venezuela er\u00f6ffnet. Lugano, August 2021 &#8211; Die Aufmerksamkeit f\u00fcr die Person in all ihren Aspekten ist eines der Grundprinzipien, auf denen BeeCare seine Arbeit aufbaut. Ein Treffen mit dem Gr\u00fcnder von Trabajo Y Persona, Alejandro Marius, f\u00fchrte zu einer sofortigen Verbindung, die sich auch dank der neuen Technologien zu einer Zusammenarbeit entwickelt hat. Trabajo Y Persona ist ein 2009 in Caracas gegr\u00fcndeter Verein, der sich zum Ziel gesetzt hat, den Wert der Arbeit und die W\u00fcrde der Person in der venezolanischen Gesellschaft zu f\u00f6rdern. Zu seinen Projekten geh\u00f6rt ein Berufskurs f\u00fcr h\u00e4usliche Pflegeassistenten, f\u00fcr welchen BeeCare einen Ad-hoc-Schulungskurs entwickelt hat, in dem Workshops und Videos mit zoom durchgef\u00fchrt werden, die die Arbeitsmethode der Schweizer Spitex veranschaulichen. Auf einen Blick die Punkte des ersten internationalen Schulungsworkshops, von Luca Milesi, Leiter der h\u00e4uslichen Pflege bei BeeCare, der die Arbeitsweise der Tessiner Spitex beschrieben hat. BeeCare ist eine Spitex, die aus der direkten Erfahrung mit der h\u00e4uslichen Pflege eines Familienmitglieds, einiger ihrer Gr\u00fcnder und Mitarbeiter, entstanden ist. BeeCare wurde als Antwort auf ein Bed\u00fcrfnis geboren und wir haben die Arbeit der h\u00e4uslichen Pflege durch die Begegnung mit den Familien entwickelt. Unsere Arbeitsweise geht auf die Vision zur\u00fcck, was es bedeutet, f\u00fcr jemanden zu sorgen. F\u00fcr BeeCare bedeutet die Pflege eines Menschen in erster Linie, ihn zu lieben. Auch die Mitarbeiter profitieren von dieser Methode, und viele unserer Pflegekr\u00e4fte empfinden gro\u00dfe Freude an ihrer Arbeit. Es ist wichtig, auf die Bed\u00fcrfnisse unserer Mitarbeiter einzugehen, damit sie sich zun\u00e4chst willkommen f\u00fchlen und sich so auf das Leid, welchem sie begegnen, einlassen k\u00f6nnen: der Mitarbeiter pflegt und betreut besser, wenn er selbst gut umsorgt wird. Wir haben erkannt, dass es notwendig ist sich einf\u00fchlend in die H\u00e4user der Patienten zu begeben um so ein Vertrauensverh\u00e4ltnis aufzubauen, welches die Grundlage f\u00fcr den Aufbau der Arbeit bildet. Auf organisatorischer Ebene agiert BeeCare als Vermittler, um die Beziehung zwischen Krankenschwestern, h\u00e4uslichen Assistenten und Familien so weit wie m\u00f6glich zu erleichtern. Die direkte Beziehung zwischen Pflegekraft und Familie birgt n\u00e4mlich ein gro\u00dfes Risiko: Die Familie hat Angst, der Pflegekraft mitzuteilen, dass bestimmte Arbeitspunkte verbessert werden m\u00fcssen, weil sie bef\u00fcrchtet, sie zu verlieren. Oder die Pflegekraft akzeptiert neue Bedingungen, weil sie bef\u00fcrchtet, ihren Arbeitsplatz zu verlieren. Wir sind ein ernstzunehmender Gespr\u00e4chspartner f\u00fcr die Familien und begleiten das Personal bei der Aus\u00fcbung seiner Arbeit. F\u00fcr uns ist es wichtig, den Menschen als Person zu behandeln, ein grundlegender Punkt, der in seiner Einfachheit niemals als selbstverst\u00e4ndlich angesehen wird. Wir verlangen von unseren Betreuern ein w\u00f6chentliches Feedback und bieten ihnen angemessene Schichten an. Bestimmt lassen wir sie nie allein und oft erz\u00e4hlen uns die Mitarbeiter von den dramatischsten Situationen, mit denen sie konfrontiert sind. Wir legen gro\u00dfen Wert auf die st\u00e4ndige Weiterbildung aller Mitarbeiter, vom F\u00fchren eines Pflegetagebuchs \u00fcber die Lagerung von Lebensmitteln bis hin zu Sprachkursen, um auch nicht italienisch sprechenden Familien helfen zu k\u00f6nnen. Die f\u00fcr diese Art von Arbeit erforderlichen F\u00e4higkeiten sind Einf\u00fchlungsverm\u00f6gen, Fachkenntnisse in der Gesundheitsf\u00fcrsorge und Authentizit\u00e4t der Person. Das Bed\u00fcrfnis zu arbeiten reicht nicht aus, man muss auch ein Interesse an der Pflege der zu betreuenden Person haben. Eine letzte Bemerkung zur h\u00e4uslichen Pflege w\u00e4hrend der Pandemie: Die Familien waren zun\u00e4chst ver\u00e4ngstigt und wollten keine zus\u00e4tzliche Person zu Hause haben. Aber als sie mit der Unm\u00f6glichkeit konfrontiert wurden, sich alleine um ihren Angeh\u00f6rigen zu k\u00fcmmern, explodierte die Nachfrage nach h\u00e4uslicher Pflege erneut. BeeCare hat alle Ma\u00dfnahmen ergriffen, um einen Schutzplan zu erstellen und alle Hygiene- und Verhaltensvorschriften einzuhalten, um weiterhin sicher arbeiten zu k\u00f6nnen. Die \u00dcberlegungen zu der bei BeeCare angewandten Arbeitsmethode wurden mit allen h\u00e4uslichen Pflegehelfern in der Ausbildung bei Trabajo Y Persona in Venezuela geteilt, wodurch ein internationaler Dialog \u00fcber ein aktuelles Thema in Gang gesetzt wurde, welches fr\u00fcher oder sp\u00e4ter jeden betrifft: die Pflege eines geliebten Menschen auf die, f\u00fcr alle beteiligten, beste und nachhaltigste Weise.<\/p>\n","protected":false},"author":1,"featured_media":237066,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-246809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/246809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=246809"}],"version-history":[{"count":0,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/246809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media\/237066"}],"wp:attachment":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=246809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/categories?post=246809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/tags?post=246809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}