{"id":246484,"date":"2021-07-14T09:21:11","date_gmt":"2021-07-14T07:21:11","guid":{"rendered":"https:\/\/stg.beecare.ch\/?p=246484"},"modified":"2024-06-24T09:47:04","modified_gmt":"2024-06-24T07:47:04","slug":"covid-19-impfung-beecare-gesundheitsfachkrafte-zu-90-geimpft","status":"publish","type":"post","link":"https:\/\/stg.beecare.ch\/de\/news\/covid-19-impfung-beecare-gesundheitsfachkrafte-zu-90-geimpft\/","title":{"rendered":"Covid-19-Impfung: BeeCare-Gesundheitsfachkr\u00e4fte zu 90% geimpft"},"content":{"rendered":"<p>Jedes Jahr fordern wir auf Dr\u00e4ngen des <strong>Kantonsarztes<\/strong> unser Gesundheitspersonal auf, sich gegen Grippe impfen zu lassen. Die Einhaltung ist nie vollst\u00e4ndig, sondern auch abh\u00e4ngig vom Gesundheitszustand der einzelnen Personen.<\/p>\n<p>\u00c4rzte, die mit uns zusammenarbeiten und in Spit\u00e4lern t\u00e4tig sind, haben uns best\u00e4tigt, dass auch in diesen Einrichtungen die Beteiligung an der Grippeimpfung des Gesundheitspersonals nie vollst\u00e4ndig sein kann.<\/p>\n<p>Es war daher eine gro\u00dfe Genugtuung, als die <a href=\"https:\/\/stg.beecare.ch\/news\/impfung-covid-19-fuer-senioren-zuhause\/\" target=\"_blank\" rel=\"noopener\"><strong>Impfung gegen Covid-19<\/strong><\/a>, die hohe Beteiligung unseres Personals an der Impfung, \u00fcber 90%, zu sehen.<\/p>\n<p>Die Entscheidung, die Impfung gegen das <a href=\"https:\/\/stg.beecare.ch\/news\/covid-19-informationen-und-empfehlungen\/\" target=\"_blank\" rel=\"noopener\">Covid-19<\/a> erh\u00f6ht die Eind\u00e4mmung der Pandemie und den Schutz derjenigen, die sich aus verschiedenen Gr\u00fcnden nicht impfen lassen k\u00f6nnen.<\/p>\n<p>Wir fragten dann die wenigen Personen, die sich nicht geimpft hatten, nach dem Grund f\u00fcr ihr Z\u00f6gern: die meisten erw\u00e4hnten die Angst im Zusammenhang mit dem Impfstoff. Gemeinsam sprachen wir dar\u00fcber und erinnerten sie daran, <strong>wie wichtig es ist, dass die Mitarbeiter von BeeCare geimpft sind<\/strong>, und forderten sie auf, verantwortungsbewusst zu handeln; denn je mehr Menschen geimpft sind, desto geringer ist die Belastung f\u00fcr das Gesundheitssystem und die Kosten f\u00fcr die Gemeinschaft.<\/p>\n<blockquote><p>Jetzt ist unser Gesundheitspersonal zu 90% geimpft (oder geheilt durch Covid-19).<\/p><\/blockquote>\n<p>Impfstoffe sind die konkreteste Hoffnung, diese Pandemie zu bek\u00e4mpfen, und unsere Mitarbeiter haben es als ihre pers\u00f6nliche Pflicht angesehen, sich zu impfen, um sich selbst und insbesondere unsere Patienten zu sch\u00fctzen. Impfen ist eine soziale und staatsb\u00fcrgerliche Verantwortung: Wir tun es nicht nur f\u00fcr uns selbst, sondern f\u00fcr alle, die uns nahestehen.<\/p>\n<p><a href=\"\/das-team\/\" target=\"_blank\" rel=\"noopener\"><strong>Tommaso Gianella<\/strong><\/a>, Direktor und Mitbegr\u00fcnder von <strong>BeeCare<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jedes Jahr fordern wir auf Dr\u00e4ngen des Kantonsarztes unser Gesundheitspersonal auf, sich gegen Grippe impfen zu lassen. Die Einhaltung ist nie vollst\u00e4ndig, sondern auch abh\u00e4ngig vom Gesundheitszustand der einzelnen Personen. \u00c4rzte, die mit uns zusammenarbeiten und in Spit\u00e4lern t\u00e4tig sind, haben uns best\u00e4tigt, dass auch in diesen Einrichtungen die Beteiligung an der Grippeimpfung des Gesundheitspersonals nie vollst\u00e4ndig sein kann. Es war daher eine gro\u00dfe Genugtuung, als die Impfung gegen Covid-19, die hohe Beteiligung unseres Personals an der Impfung, \u00fcber 90%, zu sehen. Die Entscheidung, die Impfung gegen das Covid-19 erh\u00f6ht die Eind\u00e4mmung der Pandemie und den Schutz derjenigen, die sich aus verschiedenen Gr\u00fcnden nicht impfen lassen k\u00f6nnen. Wir fragten dann die wenigen Personen, die sich nicht geimpft hatten, nach dem Grund f\u00fcr ihr Z\u00f6gern: die meisten erw\u00e4hnten die Angst im Zusammenhang mit dem Impfstoff. Gemeinsam sprachen wir dar\u00fcber und erinnerten sie daran, wie wichtig es ist, dass die Mitarbeiter von BeeCare geimpft sind, und forderten sie auf, verantwortungsbewusst zu handeln; denn je mehr Menschen geimpft sind, desto geringer ist die Belastung f\u00fcr das Gesundheitssystem und die Kosten f\u00fcr die Gemeinschaft. Jetzt ist unser Gesundheitspersonal zu 90% geimpft (oder geheilt durch Covid-19). Impfstoffe sind die konkreteste Hoffnung, diese Pandemie zu bek\u00e4mpfen, und unsere Mitarbeiter haben es als ihre pers\u00f6nliche Pflicht angesehen, sich zu impfen, um sich selbst und insbesondere unsere Patienten zu sch\u00fctzen. Impfen ist eine soziale und staatsb\u00fcrgerliche Verantwortung: Wir tun es nicht nur f\u00fcr uns selbst, sondern f\u00fcr alle, die uns nahestehen. Tommaso Gianella, Direktor und Mitbegr\u00fcnder von BeeCare<\/p>\n","protected":false},"author":1,"featured_media":238057,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-246484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/246484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=246484"}],"version-history":[{"count":0,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/246484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media\/238057"}],"wp:attachment":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=246484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/categories?post=246484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/tags?post=246484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}