{"id":244846,"date":"2023-11-20T10:52:58","date_gmt":"2023-11-20T08:52:58","guid":{"rendered":"https:\/\/stg.beecare.ch\/?p=244846"},"modified":"2023-12-27T18:32:38","modified_gmt":"2023-12-27T16:32:38","slug":"der-korper-als-instrument-der-kommunikation-des-erinnerns-und-der-interaktion-beecare-assistentinnen-erzahlen","status":"publish","type":"post","link":"https:\/\/stg.beecare.ch\/de\/news\/der-korper-als-instrument-der-kommunikation-des-erinnerns-und-der-interaktion-beecare-assistentinnen-erzahlen\/","title":{"rendered":"Der K\u00f6rper als Instrument der Kommunikation, des Erinnerns und der Interaktion; BeeCare-Assistentinnen erz\u00e4hlen"},"content":{"rendered":"<p>Am 28. Oktober fand in Lugano die zweite von <a href=\"https:\/\/www.gincoticino.ch\/\" rel=\"nofollow noopener noreferrer\" target=\"_blank\"><strong>Ginco Ticino &#8211; gruppo invecchiamento consapevole<\/strong><\/a> organisierte Konferenz zum Thema &#171;Gehirn, K\u00f6rper und Theaterkunst: Wohlbefinden und verk\u00f6rperte Beziehungen&#187; statt, an der auch mehrere BeeCare-Assistentinnen teilnahmen.<\/p>\n<p>Eine von ihnen ist<strong> Barbara Danelon<\/strong>, die seit sieben Jahren f\u00fcr BeeCare Team Minusio arbeitet und \u00fcber Erfahrungen als Kinderbetreuerin verf\u00fcgt. Sie war sehr beeindruckt vom Vortrag des <strong>Doktors Mauro Adenzato<\/strong>, Professor an der Fakult\u00e4t f\u00fcr Psychologie der Universit\u00e4t Turin, der behauptet, dass die Anzahl der Personen, mit denen ein <a href=\"https:\/\/it.wikipedia.org\/wiki\/Individuum\" target=\"_blank\" rel=\"noopener\">Subjekt<\/a> stabile soziale Beziehungen unterhalten kann, d.h. Beziehungen, in denen ein Individuum die Identit\u00e4t jeder Person kennt, 150 Individuen betr\u00e4gt. Der Mensch ist ein geselliges Tier, er muss mit anderen Individuen in Kontakt treten und interagieren. Ich existiere, weil du existierst; wir n\u00e4hern uns und gewinnen Kraft aus den emotionalen Bindungen um uns herum.<\/p>\n<p><em>&#171;Die Arbeit, die ich mache, f\u00fchrt dazu, dass ich mit vielen Menschen interagiere, nicht nur mit der zu betreuenden Person, sondern auch mit Familienmitgliedern, Angeh\u00f6rigen und den verantwortlichen Fachleuten. Zu Beginn war ich eher sch\u00fcchtern, aber mit der Zeit habe ich gelernt, mich sehr gut mit Menschen zu unterhalten. Ich stelle mich ohne Angst Realit\u00e4ten, die mir vorher unbekannt waren. Diese Arbeit hat mich sehr bereichert.&#187;<\/em> sagt Barbara D.<\/p>\n<h2>Aus der Komfortzone herauskommen<\/h2>\n<p>Ein weiterer von den Mitarbeiterinnen sehr gesch\u00e4tzter Moment war der Vortrag von <strong>Doc Riccardo Pignatti<\/strong>, Psychologe mit Spezialisierung auf individuelle Psychotherapie mit hypnotischer Ausrichtung und Theaterimprovisator, der die Zuh\u00f6rer mit einfachen Atem\u00fcbungen dazu brachte, aus ihrer Komfortzone herauszukommen. Die Rolle der Betreuerin und Haushaltshilfe erfordert eine wichtige Beziehungsf\u00e4higkeit, wie Barbara D. erkl\u00e4rt:<\/p>\n<p><em>&#171;Aus der eigenen Komfortzone herauszutreten, kann aufw\u00fchlend sein. Wenn ich daran denke, einen neuen Nutzer zu treffen, wei\u00df ich nie, was mich erwartet. Ich erinnere mich an einen der ersten Menschen, den ich traf; ein eigenartiger Mann, der in einer etwas d\u00fcsteren Umgebung lebte, die mich nerv\u00f6s machte. Ich musste geduldig sein und die Person gut kennen lernen. Schlie\u00dflich gelang es uns, eine gute Beziehung aufzubauen. Man darf nie aufgeben.&#187;<\/em><\/p>\n<h2>Zusammenpassen<\/h2>\n<p>Der K\u00f6rper ist ein grundlegendes Kommunikationsmittel, betonte der Schauspieler <strong>Dante Carbini<\/strong> in seiner Rede. In der Beziehung muss der eine das Bed\u00fcrfnis des anderen erkennen und nur durch das gemeinsame Einstimmen findet ein Austausch statt. Wie in einem Orchester, wo jeder sein Instrument stimmt und wir dann alle auf denselben Ton einstimmen.<\/p>\n<p><em>&#171;Wir wurden darauf aufmerksam gemacht, wie bestimmte Instrumente f\u00fcr zwischenmenschliche Beziehungen funktionieren und wie Beziehungen durch st\u00e4ndigen Austausch Gestalt annehmen&#187;<\/em> bekr\u00e4ftigt <strong>Barbara Gioacchini<\/strong>, Assistentin f\u00fcr Heimpflege bei BeeCare, die wie ihre Kolleginnen an der von <em>Ginco<\/em> <em>Ticino<\/em> organisierten Konferenz teilnahm.<\/p>\n<p>Der Geist besteht nicht nur aus dem Gehirn, sondern auch aus der Interaktion mit dem K\u00f6rper. Es ist in der Tat sehr wichtig, seinen eigenen K\u00f6rper und sich selbst zu kennen, um eine gute Beziehung zu anderen aufzubauen. Wir sind r\u00e4umlich ausgedehnte K\u00f6rper, die miteinander interagieren; wenn die andere Person spricht, h\u00f6re ich zu und nicke. Wir sind eine aufnahmef\u00e4hige Einheit, ein m\u00e4chtiger Resonanzboden:<\/p>\n<p><em>Der K\u00f6rper ist einer, der mit anderen um ihn herum interagiert und Beziehungen herstellt. Zurzeit habe ich nicht mit Demenzkranken zu tun, meine Patienten sind sehr klar im Kopf, aber es ist trotzdem wichtig, die Person, die vor mir steht, jeden Tag zu beobachten, denn jeder Tag ist anders <\/em>, schlie\u00dft Barbara G.<\/p>\n<h2>Das Ged\u00e4chtnis des K\u00f6rpers<\/h2>\n<p><strong>Dr. Thomas Fuchs<\/strong>, Professor an der Psychiatrischen Universit\u00e4tsklinik Heidelberg, erl\u00e4uterte in seinem Vortrag auf der Tagung, dass das K\u00f6rperged\u00e4chtnis selbst eine grundlegende Ressource f\u00fcr die Identit\u00e4tsfindung im Alter ist. Es gibt n\u00e4mlich ein autobiografisches Ged\u00e4chtnis, das mit der Zeit verloren geht, insbesondere wenn Demenz-Krankheiten auftreten, w\u00e4hrend im K\u00f6rper die Erinnerung an die Vergangenheit weiterlebt. Dieses Konzept veranschaulichte Dr. Fuchs mit einem Beispiel, das <strong>Lya Bezzola<\/strong>, die seit fast f\u00fcnf Jahren bei BeeCare als Betreuerin und Haushaltshilfe t\u00e4tig ist, sehr beeindruckte:<\/p>\n<p><em>&#171;Ich war beeindruckt, als der Professor ein Dia zeigte, das die Situation eines \u00e4lteren Menschen mit schwerer Demenz beschrieb, der einigen Jugendlichen beim Fu\u00dfballspielen zuschaute, irgendwann aufstand und mit ihnen spielen ging. In diesem Moment erinnerte sich sein K\u00f6rper sehr gut, wie man mit einem Ball spielt und was dieses Spiel wohl in seinem Leben bedeutet hat&#187;. <\/em>erl\u00e4utert Lya.<\/p>\n<p>Lya hat nicht nur ein kantonales Diplom als Betreuerin, sondern auch ein Diplom in Ortho Bionomy, einer entspannenden Therapie, die aus der Osteopathie stammt. Dies hilft ihr bei der k\u00f6rperlichen Pflege einer Person, einen respektvollen Umgang und ein tieferes Wissen \u00fcber die Anatomie des menschlichen K\u00f6rpers zu haben. Der K\u00f6rper ist nicht nur ein K\u00f6rper, er hat auch eine Seele und eine erlebte Vergangenheit. Dieses Bewusstsein f\u00fchrt dazu, dass sie einen enormen Respekt vor den Menschen hat, vor allem wenn sie ihren hilfsbed\u00fcrftigen Senioren begegnet.<\/p>\n<p><em>&#171;Menschliche Werte sind manchmal viel mehr wert als Tabletten. Wir k\u00f6nnen so viel tun, um eine Verbindung zu diesen Personen herzustellen, indem wir auch darauf achten, wie wir mit unserer K\u00f6rpersprache kommunizieren und vor allem mit Herzen uns viel Zeit f\u00fcr sie zu nehmen&#187;<\/em>, sagt Lya.<\/p>\n<h2>Selbsterkenntnis, um anderen zu helfen<\/h2>\n<p>W\u00e4hrend der Konferenz wurde nicht nur den Pflegebed\u00fcrftigen, sondern auch den Pflegern viel Bedeutung beigemessen, was <strong>Francesca Matrisciano<\/strong> sehr beeindruckte. Es geht darum, sich selbst zu kennen, um anderen helfen zu k\u00f6nnen, das eigene Potenzial zu kennen und den eigenen Gef\u00fchlen zu vertrauen, um auf nat\u00fcrliche und ungezwungene Weise mit anderen Menschen umgehen zu k\u00f6nnen.<\/p>\n<p><em>&#171;Ich betreue zweimal pro Woche eine an Alzheimer erkrankte Dame. Es hat sich sofort eine wunderbare Beziehung zu ihr entwickelt; sie erkennt mich, umarmt mich, vertraut mir und h\u00f6rt mir zu. Das ist nicht immer einfach, aber ich sehe, wie wichtig es ist, zuh\u00f6ren zu k\u00f6nnen. <\/em><em>In der Vergangenheit habe ich mit zwei sehr schwierigen Menschen aus der Psychiatrie gearbeitet. Als ich bei ihnen zuhause ankam, \u00f6ffneten sie mir sofort die T\u00fcr, und ich konnte mit ihnen kommunizieren&#187;<\/em>, erz\u00e4hlt Francesca mit Wehmut.<\/p>\n<p>Francesca ist seit M\u00e4rz dieses Jahres bei BeeCare als Betreuerin und Haushaltshilfe t\u00e4tig und findet es sehr n\u00fctzlich, an Fortbildungstagen wie diesen teilzunehmen:<\/p>\n<p><em>&#171;Ich denke, es ist wichtig, geschultes Personal zu haben, deshalb sch\u00e4tze ich diese Art von Konferenzen sehr. In meiner t\u00e4glichen Arbeit sehe ich, dass ich den Menschen, die ich betreue, viel geben kann, zudem bereichern sie auch mich jeden Tag. Morgens stehe ich zufrieden auf und gehe sehr gerne zur Arbeit.&#187; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 28. Oktober fand in Lugano die zweite von Ginco Ticino &#8211; gruppo invecchiamento consapevole organisierte Konferenz zum Thema &#171;Gehirn, K\u00f6rper und Theaterkunst: Wohlbefinden und verk\u00f6rperte Beziehungen&#187; statt, an der auch mehrere BeeCare-Assistentinnen teilnahmen. Eine von ihnen ist Barbara Danelon, die seit sieben Jahren f\u00fcr BeeCare Team Minusio arbeitet und \u00fcber Erfahrungen als Kinderbetreuerin verf\u00fcgt. Sie war sehr beeindruckt vom Vortrag des Doktors Mauro Adenzato, Professor an der Fakult\u00e4t f\u00fcr Psychologie der Universit\u00e4t Turin, der behauptet, dass die Anzahl der Personen, mit denen ein Subjekt stabile soziale Beziehungen unterhalten kann, d.h. Beziehungen, in denen ein Individuum die Identit\u00e4t jeder Person kennt, 150 Individuen betr\u00e4gt. Der Mensch ist ein geselliges Tier, er muss mit anderen Individuen in Kontakt treten und interagieren. Ich existiere, weil du existierst; wir n\u00e4hern uns und gewinnen Kraft aus den emotionalen Bindungen um uns herum. &#171;Die Arbeit, die ich mache, f\u00fchrt dazu, dass ich mit vielen Menschen interagiere, nicht nur mit der zu betreuenden Person, sondern auch mit Familienmitgliedern, Angeh\u00f6rigen und den verantwortlichen Fachleuten. Zu Beginn war ich eher sch\u00fcchtern, aber mit der Zeit habe ich gelernt, mich sehr gut mit Menschen zu unterhalten. Ich stelle mich ohne Angst Realit\u00e4ten, die mir vorher unbekannt waren. Diese Arbeit hat mich sehr bereichert.&#187; sagt Barbara D. Aus der Komfortzone herauskommen Ein weiterer von den Mitarbeiterinnen sehr gesch\u00e4tzter Moment war der Vortrag von Doc Riccardo Pignatti, Psychologe mit Spezialisierung auf individuelle Psychotherapie mit hypnotischer Ausrichtung und Theaterimprovisator, der die Zuh\u00f6rer mit einfachen Atem\u00fcbungen dazu brachte, aus ihrer Komfortzone herauszukommen. Die Rolle der Betreuerin und Haushaltshilfe erfordert eine wichtige Beziehungsf\u00e4higkeit, wie Barbara D. erkl\u00e4rt: &#171;Aus der eigenen Komfortzone herauszutreten, kann aufw\u00fchlend sein. Wenn ich daran denke, einen neuen Nutzer zu treffen, wei\u00df ich nie, was mich erwartet. Ich erinnere mich an einen der ersten Menschen, den ich traf; ein eigenartiger Mann, der in einer etwas d\u00fcsteren Umgebung lebte, die mich nerv\u00f6s machte. Ich musste geduldig sein und die Person gut kennen lernen. Schlie\u00dflich gelang es uns, eine gute Beziehung aufzubauen. Man darf nie aufgeben.&#187; Zusammenpassen Der K\u00f6rper ist ein grundlegendes Kommunikationsmittel, betonte der Schauspieler Dante Carbini in seiner Rede. In der Beziehung muss der eine das Bed\u00fcrfnis des anderen erkennen und nur durch das gemeinsame Einstimmen findet ein Austausch statt. Wie in einem Orchester, wo jeder sein Instrument stimmt und wir dann alle auf denselben Ton einstimmen. &#171;Wir wurden darauf aufmerksam gemacht, wie bestimmte Instrumente f\u00fcr zwischenmenschliche Beziehungen funktionieren und wie Beziehungen durch st\u00e4ndigen Austausch Gestalt annehmen&#187; bekr\u00e4ftigt Barbara Gioacchini, Assistentin f\u00fcr Heimpflege bei BeeCare, die wie ihre Kolleginnen an der von Ginco Ticino organisierten Konferenz teilnahm. Der Geist besteht nicht nur aus dem Gehirn, sondern auch aus der Interaktion mit dem K\u00f6rper. Es ist in der Tat sehr wichtig, seinen eigenen K\u00f6rper und sich selbst zu kennen, um eine gute Beziehung zu anderen aufzubauen. Wir sind r\u00e4umlich ausgedehnte K\u00f6rper, die miteinander interagieren; wenn die andere Person spricht, h\u00f6re ich zu und nicke. Wir sind eine aufnahmef\u00e4hige Einheit, ein m\u00e4chtiger Resonanzboden: Der K\u00f6rper ist einer, der mit anderen um ihn herum interagiert und Beziehungen herstellt. Zurzeit habe ich nicht mit Demenzkranken zu tun, meine Patienten sind sehr klar im Kopf, aber es ist trotzdem wichtig, die Person, die vor mir steht, jeden Tag zu beobachten, denn jeder Tag ist anders , schlie\u00dft Barbara G. Das Ged\u00e4chtnis des K\u00f6rpers Dr. Thomas Fuchs, Professor an der Psychiatrischen Universit\u00e4tsklinik Heidelberg, erl\u00e4uterte in seinem Vortrag auf der Tagung, dass das K\u00f6rperged\u00e4chtnis selbst eine grundlegende Ressource f\u00fcr die Identit\u00e4tsfindung im Alter ist. Es gibt n\u00e4mlich ein autobiografisches Ged\u00e4chtnis, das mit der Zeit verloren geht, insbesondere wenn Demenz-Krankheiten auftreten, w\u00e4hrend im K\u00f6rper die Erinnerung an die Vergangenheit weiterlebt. Dieses Konzept veranschaulichte Dr. Fuchs mit einem Beispiel, das Lya Bezzola, die seit fast f\u00fcnf Jahren bei BeeCare als Betreuerin und Haushaltshilfe t\u00e4tig ist, sehr beeindruckte: &#171;Ich war beeindruckt, als der Professor ein Dia zeigte, das die Situation eines \u00e4lteren Menschen mit schwerer Demenz beschrieb, der einigen Jugendlichen beim Fu\u00dfballspielen zuschaute, irgendwann aufstand und mit ihnen spielen ging. In diesem Moment erinnerte sich sein K\u00f6rper sehr gut, wie man mit einem Ball spielt und was dieses Spiel wohl in seinem Leben bedeutet hat&#187;. erl\u00e4utert Lya. Lya hat nicht nur ein kantonales Diplom als Betreuerin, sondern auch ein Diplom in Ortho Bionomy, einer entspannenden Therapie, die aus der Osteopathie stammt. Dies hilft ihr bei der k\u00f6rperlichen Pflege einer Person, einen respektvollen Umgang und ein tieferes Wissen \u00fcber die Anatomie des menschlichen K\u00f6rpers zu haben. Der K\u00f6rper ist nicht nur ein K\u00f6rper, er hat auch eine Seele und eine erlebte Vergangenheit. Dieses Bewusstsein f\u00fchrt dazu, dass sie einen enormen Respekt vor den Menschen hat, vor allem wenn sie ihren hilfsbed\u00fcrftigen Senioren begegnet. &#171;Menschliche Werte sind manchmal viel mehr wert als Tabletten. Wir k\u00f6nnen so viel tun, um eine Verbindung zu diesen Personen herzustellen, indem wir auch darauf achten, wie wir mit unserer K\u00f6rpersprache kommunizieren und vor allem mit Herzen uns viel Zeit f\u00fcr sie zu nehmen&#187;, sagt Lya. Selbsterkenntnis, um anderen zu helfen W\u00e4hrend der Konferenz wurde nicht nur den Pflegebed\u00fcrftigen, sondern auch den Pflegern viel Bedeutung beigemessen, was Francesca Matrisciano sehr beeindruckte. Es geht darum, sich selbst zu kennen, um anderen helfen zu k\u00f6nnen, das eigene Potenzial zu kennen und den eigenen Gef\u00fchlen zu vertrauen, um auf nat\u00fcrliche und ungezwungene Weise mit anderen Menschen umgehen zu k\u00f6nnen. &#171;Ich betreue zweimal pro Woche eine an Alzheimer erkrankte Dame. Es hat sich sofort eine wunderbare Beziehung zu ihr entwickelt; sie erkennt mich, umarmt mich, vertraut mir und h\u00f6rt mir zu. Das ist nicht immer einfach, aber ich sehe, wie wichtig es ist, zuh\u00f6ren zu k\u00f6nnen. In der Vergangenheit habe ich mit zwei sehr schwierigen Menschen aus der Psychiatrie gearbeitet. Als ich bei ihnen zuhause ankam, \u00f6ffneten sie mir sofort die T\u00fcr, und ich konnte mit ihnen kommunizieren&#187;, erz\u00e4hlt Francesca mit Wehmut. Francesca ist seit M\u00e4rz dieses Jahres bei BeeCare als Betreuerin und Haushaltshilfe t\u00e4tig und findet es sehr n\u00fctzlich, an Fortbildungstagen wie diesen teilzunehmen: &#171;Ich denke, es ist wichtig, geschultes Personal zu haben, deshalb sch\u00e4tze ich diese Art von Konferenzen sehr.<\/p>\n","protected":false},"author":1,"featured_media":244458,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-244846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/244846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=244846"}],"version-history":[{"count":0,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/244846\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media\/244458"}],"wp:attachment":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=244846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/categories?post=244846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/tags?post=244846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}