{"id":239153,"date":"2020-10-19T12:21:03","date_gmt":"2020-10-19T10:21:03","guid":{"rendered":"https:\/\/stg.beecare.ch\/?p=239153"},"modified":"2023-05-08T16:00:17","modified_gmt":"2023-05-08T14:00:17","slug":"beecare-erwirbt-das-unternehmen-gruppo-salute-im-raum-mendrisio","status":"publish","type":"post","link":"https:\/\/stg.beecare.ch\/de\/news\/beecare-erwirbt-das-unternehmen-gruppo-salute-im-raum-mendrisio\/","title":{"rendered":"BeeCare erwirbt das Unternehmen Gruppo Salute im Raum Mendrisio"},"content":{"rendered":"<p>BeeCare hat im Fr\u00fchjahr\/Sommer 2020 das <strong>Spitex Gruppo Salute in Vacallo<\/strong> im Raum Mendrisio erworben und dabei sowohl die Patienten als auch das Personal des Pflegedienstes in Mendrisio \u00fcbernommen. Es handelt sich um eine \u00dcbernahme nach dem Leitprinzip unseres <strong>Spitex<\/strong>: Sorge tragen, sich um die Mitmenschen k\u00fcmmern.<\/p>\n<p>Isabelle Dufour, Gr\u00fcnderin des Spitex Gruppo Salute, erz\u00e4hlt uns gemeinsam mit <a href=\"\/de\/team\/\">Anna Moretto, Direktorin f\u00fcr den Gesundheitsdienst bei BeeCare<\/a>, wie es zu dieser \u00dcbernahme gekommen ist.<\/p>\n<h2>Kontinuit\u00e4t f\u00fcr die Patient\/innen und f\u00fcr das Personal<\/h2>\n<p>\u201e<em>Ungef\u00e4hr vor einem Jahr hat mich BeeCare zum ersten Mal kontaktiert, um \u00fcber eine \u00dcbernahme des <\/em><strong><em>Spitex<\/em><\/strong><em> zu sprechen, das ich vor einigen Jahren gegr\u00fcndet habe. Da der Zeitpunkt gekommen ist, mich aus gesundheitlichen Gr\u00fcnden und mangels Nachfolger und Energie f\u00fcr eine Umstrukturierung des Pflegedienstes aus dem Berufsleben zur\u00fcckzuziehen, habe ich beschlossen, das Angebot von BeeCare anzunehmen, nicht zuletzt auch weil mir viel daran lag, das Spitex in H\u00e4nde zu geben, die nicht nur die von uns betreuten Personen, sondern auch unsere Mitarbeiter \u00fcbernehmen.<\/em><\/p>\n<p><em>Da unser Pflegepersonal bereits seit Jahren bei Gruppo Salute arbeitet, schien mir das die einzig richtige L\u00f6sung. Um die Patientinnen und Patienten BeeCare anzuvertrauen, habe ich einen Brief an alle betroffenen Familie geschrieben, um sie \u00fcber die M\u00f6glichkeit zu informieren, zu wechseln, und anschliessend hat auch BeeCare mit allen Familien Kontakt aufgenommen<\/em>\u201c, so <strong>Isabelle Dufour<\/strong>.<\/p>\n<p>\u201e<em>Ich habe viele Jahre als selbstst\u00e4ndige Krankenpflegerin gearbeitet, und wenn ich eine Aushilfe brauchte, war es nicht immer einfach, jemanden zu finden. Aus diesem Grund habe ich 2004 einen Spitex-Dienst ins Leben gerufen, um Personal einstellen und den Patientinnen und Patienten eine Betreuung rund um die Uhr bieten zu k\u00f6nnen.<\/em><\/p>\n<p><em>Ich habe mich f\u00fcr <\/em><strong><em>BeeCare<\/em><\/strong><em> entschieden, weil das Unternehmen einen guten Ruf hat und ich einen seri\u00f6sen Pflegedienst wollte. Ein <\/em><strong><em>guter Spitex-Dienst muss Qualit\u00e4t, Zuverl\u00e4ssigkeit und Kontinuit\u00e4t in der Pflege<\/em><\/strong> bieten\u201c, schliesst die Krankenpflegerin ab.<\/p>\n<p><strong>Sorge tragen, jederzeit<\/strong><\/p>\n<p>\u201e<em>Die \u00dcbergabe der betreuten Personen und des Personals in kurzer Zeit war zweifellos eine Herausforderung\u201c, <\/em>erl\u00e4utert <strong>Anna Moretto<\/strong>, Leiterin des Gesundheitsdienstes bei <strong>BeeCare<\/strong><em>.<\/em><\/p>\n<p><em>\u201eErst haben wir alle vom Kantonsarzt geforderten Gesundheitsdaten digitalisiert und dann die Patientinnen und Patienten kennen gelernt: zun\u00e4chst anhand der uns vorliegenden Dokumente und dann pers\u00f6nlich. Dabei haben wir besonders auch auf die individuellen Anforderungen der Familien und die Schichten des Pflegepersonals geachtet. In der \u00dcbergangsphase war es sehr wichtig, die Familien hinsichtlich der Kontinuit\u00e4t der Pflegeleistungen abzusichern, uns auf sie einzustellen&#8230; wie wir bei BeeCare sagen: Sorge zu tragen. Ausserdem war es sehr wichtig, den Familien zu versichern, dass das Pflegepersonal nicht gewechselt worden w\u00e4re<\/em>.\u201c<\/p>\n<p>\u201e<em>Der \u00dcbergang hat reibungslos funktioniert<\/em>\u201c, <strong>kommentiert Anna Moretto<\/strong>, \u201e<em>denn im Mittelpunkt f\u00fcr uns alle stand das Ziel, Sorge f\u00fcr die anderen zu tragen \u2013 in diesem Fall die neuen Patientinnen und Patienten und die neuen Mitarbeiter.<\/em><\/p>\n<p><em>Unser Motto in die Praxis umzusetzen war der Schl\u00fcssel f\u00fcr den Erfolg. Nicht nur bei der \u00dcbernahme des Spitex-Dienstes <\/em><strong><em>Gruppo Salute<\/em><\/strong><em>, sondern generell, wenn wir mit einer Familie zu tun haben, die den Pflegedienst wechselt: Wir arbeiten grunds\u00e4tzlich mit allen einbezogenen Personen zusammen, vom behandelnden Arzt bis hin zum Pflegepersonal.<\/em><em> <\/em><\/p>\n<p><em>Manchmal h\u00e4lt man es f\u00fcr selbstverst\u00e4ndlich, dass Mitarbeiter oder Patient\/innen Ver\u00e4nderungen hinnehmen, weil sie dazu gezwungen sind. Dagegen ist es sehr wichtig, ihnen zuzuh\u00f6ren und ihnen Sicherheit zu geben, indem man bereit ist, sich zusammenzusetzen und alle Fragen zu besprechen<\/em>.\u201c<\/p>\n<p>Dank des neuen Netzes mit Mitarbeitern in der Umgebung von Mendrisio, die nun Teil von BeeCare sind, ist unser <a href=\"https:\/\/stg.beecare.ch\/de\/\">Spitex in Mendrisio<\/a> in der Lage, eine gr\u00f6ssere Anzahl Familien in dieser Gegend zu betreuen. Und das mit dem im Tessin \u00fcblichen Schwerpunkt auf lokale Synergien.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BeeCare hat im Fr\u00fchjahr\/Sommer 2020 das Spitex Gruppo Salute in Mendrisio erworben und dabei sowohl die Patient\/innen als auch das Personal des Pflegedienstes in Mendrisio \u00fcbernommen.<\/p>\n","protected":false},"author":1,"featured_media":30611,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-239153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/239153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=239153"}],"version-history":[{"count":0,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/239153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media\/30611"}],"wp:attachment":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=239153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/categories?post=239153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/tags?post=239153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}