{"id":239072,"date":"2019-04-23T11:40:48","date_gmt":"2019-04-23T09:40:48","guid":{"rendered":"https:\/\/stg.beecare.ch\/?p=239072"},"modified":"2023-05-08T16:00:23","modified_gmt":"2023-05-08T14:00:23","slug":"wenn-krankenpflegepersonal-aufgrund-der-arbeitsbedingungen-den-beruf-aufgibt","status":"publish","type":"post","link":"https:\/\/stg.beecare.ch\/de\/news\/wenn-krankenpflegepersonal-aufgrund-der-arbeitsbedingungen-den-beruf-aufgibt\/","title":{"rendered":"Wenn Krankenpflegepersonal aufgrund der Arbeitsbedingungen den Beruf aufgibt"},"content":{"rendered":"<p>Ich m\u00f6chte hier \u00fcber den interessanten Leitartikel schreiben, den <strong>Mariano Cavolo<\/strong>, Redakteur der Fachzeitschrift ASI, im Monat M\u00e4rz in der Zeitschrift \u00fcber die T\u00e4tigkeit des Schweizer Berufsverbands der Pflegefachfrauen und Pflegefachm\u00e4nner, Sektion Tessin, geschrieben hat und dabei den im Januar dieses Jahres in der romanischen Tageszeitung 25 heures erschienenen Artikel \u201e<em>C\u2019est pour les patients que j\u2019arrete ce metier<\/em>\u201c kommentiert und dazu neue \u00dcberlegungen anstellt. Der Artikel berichtet \u00fcber eine Krankenpflegerin, die nach einer langen Ausbildung ihre berufliche T\u00e4tigkeit beginnt und nach acht Monaten (harter?) Arbeit in einem Krankenhaus infolge eines Burnout (aufgrund von schwierigen Arbeitsbedingungen auf psychologischer und organisatorischer Ebene) beschlie\u00dft, ihren erlernten Beruf aufzugeben.<\/p>\n<h2>Psychologisches Unwohlsein bringt Krankenpflegepersonal dazu, den erlernten Beruf aufzugeben<\/h2>\n<p>Mariano Cavolo erl\u00e4utert, wie die internationale Forschung im Krankenpflegesektor seit Jahren zeigt, dass <em>\u201edas Wohlergehen des Krankenpflegepersonals und damit auch die Dauer der Anstellung f\u00fcr die Qualit\u00e4t der erbrachten Leistungen entscheidend sind: Verschiedene Studien haben die Verbindung zwischen psychologischem Wohlbefinden der Angestellten und der beruflichen Leistung nachgewiesen<\/em>\u201c. Und dass folglich auch psychologisches Unwohlsein aufgrund von negativen Arbeitsbedingungen das Pflegepersonal dazu bringt, den Beruf aufzugeben.<\/p>\n<p>Der Artikel unterstreicht auch die Tatsache, dass die H\u00e4lfte der ausgebildeten Pflegekr\u00e4fte im Alter von 35 Jahren den Beruf aufgibt \u2013 gerade zu dem Zeitpunkt, in dem sie nach zehn Jahren T\u00e4tigkeit menschliche und technische Erfahrungen gesammelt haben, die in jedem Beruf von grundlegender Bedeutung sind, und das insbesondere im Gesundheitswesen. Und mehr als die H\u00e4lfte, 56%, gibt den Beruf ab 50 Jahren auf.<\/p>\n<p>Das ist jedoch ein Problem der gesamten Schweizer Wirtschaft. Mehr als 50% aller Universit\u00e4tsabsolventen sind Frauen, und ein gro\u00dfer Prozentsatz von ihnen geht in jedem Beruf \u201everloren\u201c, da wir nicht in der Lage sind, zufriedenstellende Arbeitsbedingungen f\u00fcr ein harmonisches Nebeneinander von Berufsleben und Familie zu schaffen.<\/p>\n<h2>In der Arbeitswelt gehen Talente und Arbeitskr\u00e4fte verloren<\/h2>\n<p>Die Arbeitswelt (unsere Betriebe und Unternehmen) b\u00fc\u00dft nicht nur Talente, sondern auch Arbeitskr\u00e4fte ein.<\/p>\n<p>Eine der politischen Parteien hat auch hervorgehoben, dass wir nicht so viele qualifizierte ausl\u00e4ndische Arbeitskr\u00e4fte (Grenzarbeitnehmer) br\u00e4uchten, wenn wir unsere weiblichen Arbeitskr\u00e4fte zur\u00fcckgewinnen k\u00f6nnten.<\/p>\n<p>Aber zur\u00fcck zu uns: Um nicht Personal zu verlieren, f\u00fcr das viel in die Ausbildung investiert wurde, muss laut Cavolo \u00c4nderungen die Arbeit in Krankenh\u00e4usern neu organisiert werden. Wobei allerdings hinzuzuf\u00fcgen ist, dass den Krankenh\u00e4user ohne politische Beschl\u00fcsse die H\u00e4nde gebunden sind.<br \/>Ich kann mir nicht vorstellen, dass in einem Sektor wie dem Gesundheitswesen, der sich in starkem Wachstum befindet, der Verlust von Kompetenzen aufgrund der Aufgabe des Berufs (oder wegen \u201eAbnutzung\u201c bei rein klinischer Erledigung der Arbeit) unvermeidlich ist, wenn nicht die Politik eingreift. Und dass ohne Initiativen von oben alles umsonst ist und sich nie etwas bessern wird.<\/p>\n<p>Das glaube ich nicht.<\/p>\n<p>Es ist jedoch notwendig, ein Gleichgewicht in ein effizientes Personalmanagement und eine langfristig haltbare Finanzverwaltung zu bringen und all dies praktisch und konkret im Alltag umsetzen. Es muss ins allgemeine Bewusstsein dringen, dass es im Dienstleistungssektor die Menschen sind, die den Erfolg eines Betriebs entscheiden: Sie sind es, die das Talent besitzen, das den Unterschied ausmacht.<\/p>\n<p>In unserem Fall kann daher nicht von der W\u00fcrde der Patienten gesprochen werden, wenn diejenigen, die sie pflegen und betreuen, nicht mit W\u00fcrde behandelt werden.<\/p>\n<p>Wenn finanzielle Aspekte immer Vorrang vor dem Menschen haben, sind wir zu einem System verdammt, das uns in Richtung eines sicheren Arbeitsplatzes, beim Staat, treibt, bei dem man vor solchen Aspekten sicher ist.<\/p>\n<h2>In Dienstleistungsunternehmen hat die Arbeitskraft gro\u00dfen Wert<\/h2>\n<p>In einer Dienstleistungsgesellschaft, in der viel in die technische Ausbildung des Personals investiert wird, und zwar sowohl seitens der Person selbst als auch seitens ihrer Familie und des Staates (f\u00fcr das Jahr 2011 wird von ca. 40.000 Franken pro Krankenpflegerin\/Krankenpfleger ausgegangen), hat jede Arbeitskraft gro\u00dfen Wert.<\/p>\n<p>Als Betrieb m\u00fcssen wir mehr auf der Ebene der Organisation und des Managements investieren und die Personalf\u00fchrung dahingehend verbessern, dass unsere Mitarbeiter\/innen motiviert sind, um so Personalfluktuation (mit enormen Kosten, die jedoch zu wenig ber\u00fccksichtigt werden) und den Ausfall von Personal aufgrund von Krankheit durch Ersch\u00f6pfung etc. zu vermeiden.<\/p>\n<p>Wenn wir immer nur an die Kostenkontrolle denken, dann geht dies grunds\u00e4tzlich zu Lasten des Personals. Und wir werden nie etwas \u00e4ndern k\u00f6nnen. Irgendjemand hat einmal gesagt: Wenn du immer auf die gleiche Weise \u00fcber ein Problem nachdenkst, findest du immer auch die gleiche L\u00f6sung. Um eine innovative L\u00f6sung zu finden, muss man umdenken.<\/p>\n<p>Viele Erfahrungen auf organisatorischer Ebene zeigen genau das: F\u00fcr ein Problem, das als unl\u00f6sbar galt, wurden unerwartete L\u00f6sungen gefunden, wenn sich der Denkansatz \u00e4nderte.<\/p>\n<p>In einem Beruf mit einer stark emotionalen Komponente ist dieses erzwungene Gleichgewicht zwischen finanziellen Aspekten und der Personalverwaltung offensichtlicher, ist jedoch prinzipiell in allen Berufen vorhanden. Mangelhafte organisatorische Bedingungen in Kombination mit einer hohen Arbeitslast f\u00fchren fr\u00fcher oder sp\u00e4ter zu Personalfluktuation und damit zu h\u00f6heren Kosten. Dieses Ph\u00e4nomen ist noch st\u00e4rker unter der weiblichen Bev\u00f6lkerung verbreitet. Weil Frauen schw\u00e4cher sind? Das glaube ich nicht.<\/p>\n<p>Ich glaube jedoch, dass Frauen weniger bereit sind, Tag f\u00fcr Tag und Jahr f\u00fcr Jahr schlechte Arbeitsbedingungen zu akzeptieren und sie auf lange Sicht als normal hinzunehmen und somit zuletzt vielleicht zynisch zu werden. Wie wir immer wieder sehen, k\u00fcndigen sie lieber.<\/p>\n<h2>Der Vergleich zwischen Arbeit und Familie<\/h2>\n<p>In meiner Erfahrung als Leiter der Personalverwaltung habe ich festgestellt, dass die Frauen, die den Betrieb, in dem sie besch\u00e4ftigt waren, verlassen haben (nicht unbedingt ihren Beruf aufgegeben haben, obwohl auch das geschieht), sich oft hierf\u00fcr entschieden haben, weil sie sich bewusst geworden sind, dass sie die am Arbeitsplatz verbrachte Zeit weniger bereichert hat als die Zeit mit ihrer Familie oder beim Gro\u00dfziehen ihrer Kinder oder aber bei anderen Dingen.<\/p>\n<p>Die Entscheidung ist f\u00fcr sie radikal: \u201e<em>Wenn ich mich an meinem Arbeitsplatz nicht als Mensch weiterentwickle und wenn mein Mann oder mein Lebenspartner f\u00fcr ein ausreichendes Einkommen f\u00fcr unsere Familie sorgt, dann lasse ich meine Arbeit sein und nutze die Zeit, um meine Kinder gro\u00dfzuziehen oder mir eine andere Arbeit zu suchen<\/em>.\u201c Und so kommt es, dass das K\u00fcndigungsschreiben auf dem Tisch liegt.<\/p>\n<p>Hieraus geht eindeutig hervor: Wenn in meinem Betrieb vorrangig weibliches Personal arbeitet, wie es f\u00fcr viele Pflege- und Sozialdienste (z.B. in Krankenh\u00e4usern, Reha-Kliniken, aber auch gro\u00dfe Versicherungen, schulische Einrichtungen etc.) typisch ist, kann ich es mir strategisch nicht leisten, diese Kompetenzen zu verlieren&#8230;<\/p>\n<p>Wir k\u00f6nnen nicht warten, dass die Politik entscheidet. Wir m\u00fcssen bei allem bewusster vorgehen und d\u00fcrfen die Realit\u00e4t nicht aus den Augen verlieren: dass in unseren Hochschulen mehr Frauen als M\u00e4nner ausgebildet werden (basierend auf den in den Schweizer Hochschulen und Universit\u00e4ten eingeschriebenen Studentinnen und Studenten, Quelle: Bundesamt f\u00fcr Statistik), aber dass wir dann viele von ihnen aufgrund der schlechten Arbeitsbedingungen und mangelnder Work-Life Balance verlieren.<\/p>\n<p>Die Verbesserung der Arbeitsbedingungen ist ein entscheidender Faktor f\u00fcr die Lebensqualit\u00e4t und daher strategisch f\u00fcr die Betriebe, die einen Verlust an wertvollen Kompetenzen und Know-how verhindern m\u00f6chten. Eine positive Auswirkung ist auch eine h\u00f6here Qualit\u00e4t der erbrachten Dienstleistungen. Das alles bedeutet jedoch: umdenken. Sich bewusst werden, dass ein gutes Management mittel- und langfristig Wohlstand bringt. Einen stabileren Wohlstand.<\/p>\n<p>Das Management eines Betriebs muss daf\u00fcr sorgen, dass das Personal effizient und zufrieden arbeitet. Die Betriebe, die einheimisches Personal halten m\u00f6chten, m\u00fcssen an der Qualit\u00e4t der Arbeitsbedingungen arbeiten.<\/p>\n<p>Das ist eine gro\u00dfe Herausforderung. Wenn sich die betriebsinternen Arbeitsbedingungen nicht bessern, werden diejenigen, die die Wahl, eine gute Qualifikation oder aber Kontakte haben, die ihnen neue M\u00f6glichkeiten er\u00f6ffnen, oder die in der Familie mit nur einem Einkommen leben k\u00f6nnen, den Betrieb verlassen. Ich habe oft gesehen, dass gerade die Besten gehen. Wer keine andere M\u00f6glichkeit hat, bleibt.<\/p>\n<p>Nach vielen Jahren Personalmanagement in verschiedenen nationalen und internationalen Unternehmen haben wir entschieden, ein Unternehmen zu gr\u00fcnden, in dem wir eine Reihe von Prinzipien f\u00fcr die Personalf\u00fchrung konkret umsetzen wollten, an die ich glaube und die mir zu zahlreichen Erfolgen verholfen haben, auch wenn ich ein paar Niederlagen einstecken musste.<\/p>\n<h2>Das Unternehmen und die h\u00e4usliche Alten- und Krankenpflege<\/h2>\n<p>Unser Unternehmen ist im kritischsten Bereich des Gesundheitswesens t\u00e4tig: der h\u00e4uslichen Alten- und Krankenpflege. Nachdem ich mit mehreren Krankenpflegerinnen gesprochen habe, die mir erz\u00e4hlt haben, wie sehr sie ihren Beruf lieben, dass die teils unm\u00f6glichen organisatorischen Bedingungen sie jedoch veranlasst haben, ihren Beruf aufzugeben, habe ich mich entschlossen, auch mit den Betreuten, also den Kunden der <a href=\"\/de\/\"><strong>Spitex-Einrichtungen<\/strong><\/a>, zu sprechen und ihnen zuzuh\u00f6ren.<\/p>\n<p>Die Patienten wiederum beschweren sich oft dar\u00fcber, dass das sie pflegende Personal st\u00e4ndig wechselt. Sie w\u00fcnschen sich mehr Kontinuit\u00e4t in der Betreuung.<\/p>\n<p>Auf der Grundlage dieser beiden Prinzipien haben wir <strong>BeeCare<\/strong> gegr\u00fcndet, mit dem Ziel:<\/p>\n<ol>\n<li><a href=\"\/de\/spitex\/\">Unseren Fachkr\u00e4ften die besten Arbeitsbedingungen zu bieten.<\/a><\/li>\n<li><a href=\"\/de\/unsere-leistungen\/\">Die besten Aufnahmebedingungen f\u00fcr die uns zur Pflege anvertrauten Menschen zu schaffen.<\/a><\/li>\n<\/ol>\n<p>Wir sind davon \u00fcberzeugt, dass wir die Berufe in der h\u00e4uslichen Alten- und Krankenpflege m\u00f6glichst attraktiv gestalten m\u00fcssen.<br \/>Ihre Attraktivit\u00e4t basiert auf der Selbstst\u00e4ndigkeit, Flexibilit\u00e4t und flexiblen Arbeitszeit, die wir bieten. Die ideale L\u00f6sung f\u00fcr eine Mutter.<br \/>Der Pflegeberuf ist ein anspruchsvoller Beruf, der aber auch gro\u00dfe Genugtuung bringt.<\/p>\n<p>Als Krankenpflegerin, Pflegehelferin oder Gesundheitspflegerin bei anderen Menschen zu Hause zu arbeiten, ist nicht etwas, das alle tun k\u00f6nnen. Man muss qualifiziert und bereit sein, die gesamte Verantwortung f\u00fcr den zu Hause betreuten und gepflegten Patienten zu \u00fcbernehmen. Und nicht nur einfach vorbeischauen, tun, was zu tun ist, und dann wieder zu gehen. Man muss generell alles im Blick haben \u2013 beispielsweise, ob die Wohnr\u00e4ume gel\u00fcftet wurden oder noch werden m\u00fcssen. In diesem Fall muss der Patient zuvor in ein anderes Zimmer gebracht werden, damit er nicht einem gesundheitssch\u00e4digenden Luftzug ausgesetzt ist.<\/p>\n<p>Man muss kreativ sein und sich zu helfen wissen. Man muss um Hilfe bitten k\u00f6nnen, da man oft allein beim Patienten ist, aber gewisse Dinge allein vielleicht nicht schafft. Daher muss man den Kontakt mit Angeh\u00f6rigen pflegen, um sich an diese wenden zu k\u00f6nnen.<\/p>\n<p>Vor allem aber muss man in der Lage sein, Patienten mit einer immer komplexeren Pflegesituation zu betreuen, da heute \u00fcber die h\u00e4usliche Pflege viele Krankheiten behandelt werden, die in der Vergangenheit Aufgabe eines Krankenhauses waren. Aus diesem Grund ist in diesem Beruf die Fort- und Weiterbildung so wichtig. Oft muss man sich abends das Ged\u00e4chtnis und die Kenntnisse \u00fcber neue Methoden und Techniken mit Hilfe von B\u00fcchern auffrischen.<\/p>\n<p>Die Arbeit in der h\u00e4uslichen Betreuung und Pflege erfordert aus diesem Grund gro\u00dfen Willen und Verantwortungsbewusstsein. Im Gegenzug bietet sie jedoch Selbstst\u00e4ndigkeit und pers\u00f6nlichen und realen Kontakt mit den Patienten und die Genugtuung, ihnen zu mehr Selbstst\u00e4ndigkeit und Freiheit im eigenen Heim zu verhelfen.<\/p>\n<p>Die h\u00e4usliche Betreuung und Pflege ist ein anspruchsvoller Beruf, und es besteht ein immer gr\u00f6\u00dferer Bedarf an Fachkr\u00e4ften. Gerade aus diesem Grund sollte er nicht aufgegeben, sondern an die individuellen zeitlichen M\u00f6glichkeiten angepasst werden.<\/p>\n<p>Grundvoraussetzung ist organisatorische Flexibilit\u00e4t, die heute mehr denn je gefragt ist.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich m\u00f6chte hier \u00fcber den interessanten Leitartikel schreiben, den Mariano Cavolo, Redakteur der Fachzeitschrift ASI, im Monat M\u00e4rz in der Zeitschrift \u00fcber die T\u00e4tigkeit des Schweizer Berufsverbands der Pflegefachfrauen und Pflegefachm\u00e4nner, Sektion Tessin<\/p>\n","protected":false},"author":1,"featured_media":235885,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-239072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/239072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=239072"}],"version-history":[{"count":0,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/239072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media\/235885"}],"wp:attachment":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=239072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/categories?post=239072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/tags?post=239072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}