{"id":239040,"date":"2019-01-28T14:44:03","date_gmt":"2019-01-28T12:44:03","guid":{"rendered":"https:\/\/stg.beecare.ch\/?p=239040"},"modified":"2023-05-08T16:00:32","modified_gmt":"2023-05-08T14:00:32","slug":"gut-gemachte-arbeit","status":"publish","type":"post","link":"https:\/\/stg.beecare.ch\/de\/news\/gut-gemachte-arbeit\/","title":{"rendered":"Gut gemachte Arbeit"},"content":{"rendered":"<blockquote>\n<p>\u201eEs gab Zeiten, in denen Arbeiter keine \u201eDiener\u201c waren. Sie arbeiteten. Sie arbeiteten mit W\u00fcrde, einer absoluten W\u00fcrde, wie es sich geh\u00f6rt. Das Bein eines Stuhles musste gut geschreinert sein. Das war nur nat\u00fcrlich, selbstverst\u00e4ndlich. Es war eine Spitzenleistung. Es musste nicht wegen dem Lohn oder proportional zum Lohn gut geschreinert sein. Es musste nicht f\u00fcr den Meister oder Kenner und auch nicht f\u00fcr die Kunden des Meisters gut geschreinert sein. Es musste an sich, f\u00fcr sich, aus seiner Natur heraus gut geschreinert sein.<\/p>\n<p>Die tief in der Rasse verwurzelte Tradition, die Geschichte, ein absoluter Anspruch, die W\u00fcrde verlangten, dass das Stuhlbein gut geschreinert war. Und dass jeder Teil des Stuhles gut geschreinert war. Und auch jeder Teil des Stuhles, der nicht sichtbar war, wurde mit der gleichen Perfektion wie alle sichtbaren Teile gefertigt. Nach dem gleichen Prinzip wie unsere Kathedralen. Und nur ich \u2013 inzwischen so entartet \u2013 mache mir jetzt so viele Gedanken.<\/p>\n<p>F\u00fcr die Menschen damals gab es nicht einmal den Ansatz solcher \u00dcberlegungen.<\/p>\n<p>Da war ihre Arbeit. Und es lie\u00df sich gut arbeiten. Es ging nicht darum, gesehen oder nicht gesehen zu werden. Die Arbeit selbst musste gut gemacht werden.\u201c<\/p>\n<p>(Frei aus:) <strong>Charles Peguy, L\u2019Argent <\/strong><\/p>\n<\/blockquote>\n<p>Sie fragen sich vielleicht, was dies mit der h\u00e4uslichen Alten- und Krankenpflege, mit \u00e4lteren Menschen, Spitex, Krankenpflegepersonal usw. zu tun hat&#8230; Nun, es hat mit allem zu tun und ich m\u00f6chte Ihnen sagen, warum es f\u00fcr uns wichtig ist. Dieser kurze Auszug des Schriftstellers Charles Peguy (1873-1914) erl\u00e4utert eine Arbeitsmethode, die wir jeden Tag von unseren Mitarbeitern verlangen \u2013 sei es Krankenpflegepersonal, Pflegehelfer\/innen, Gesundheitshelfer\/innen oder Altenpfleger\/innen (Betreuer\/innen). Es ist keine neue Methode und auch keine antike Methode. Es ist eine Methode, die im Laufe der Jahre verloren gegangen ist und die wir wieder in die Gegenwart holen m\u00f6chten.<\/p>\n<h2>Gut arbeiten hat einen Vorteil<\/h2>\n<p>Gut arbeiten hat, wie Peguy schreibt, einen Vorteil: das Bewusstsein, das gut gemacht zu haben, das man in dem Moment machen sollte.<\/p>\n<p>Eine Insulininjektion f\u00fcr eine \u00e4ltere Dame, die an Diabetes erkrankt ist, ist ein rein technischer Vorgang, den man ganz einfach gut erledigen kann. Eine Insulininjektion machen und bemerken, dass im K\u00fchlschrank abgelaufene Milch steht, ist dagegen die Methode, bei der wir uns bewusst werden, dass wir unsere Arbeit gut gemacht haben. Und die \u00e4ltere Generation wei\u00df das nur zu gut. In ihrem Leben stand diese Methode im Arbeitsalltag immer im Mittelpunkt.<\/p>\n<p>Und unsere Aufgabe heute ist es, diese \u201eVision\u201c wieder zum Leben zu erwecken. Jemandem zu Dienst sein, bedeutet nicht, Diener im negativen Sinne zu sein, sondern bedeutet, eine Mission zu verfolgen.<\/p>\n<p>F\u00fcr uns bei <strong>BeeCare<\/strong> ist es eine Mission in der h\u00e4uslichen Alten- und Krankenpflege, denjenigen Unterst\u00fctzung zu bieten, die uns darum bitten. Ohne unsere Verantwortung dabei zu untersch\u00e4tzen oder nur zum Teil zu erf\u00fcllen.<\/p>\n<p>Wir betrachten alles immer als Gesamtheit und arbeiten gemeinsam daran. Aus diesem Grund wird auch alles immer mit der Familie oder mit der zu betreuenden oder zu pflegenden Person abgesprochen. Gut gemachte Arbeit ist gemeinsam erledigte Arbeit.<\/p>\n<p>Mit Diskretion, Engagement und Liebe f\u00fcr die eigene Arbeit.<\/p>\n<p>Die gleichen Zutaten, mit denen Kathedralen gebaut wurden. Alle, die in der Stadt oder auf dem Land in der h\u00e4uslichen Alten- und Krankenpflege t\u00e4tig sind, m\u00fcssen sich dieser Philosophie einer gut, sorgf\u00e4ltig und mit Liebe gemachten Arbeit bewusst sein.<\/p>\n<p>Das bedeutete Professionalit\u00e4t gestern und das ist Professionalit\u00e4t auch heute.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie fragen sich vielleicht, was dies mit der h\u00e4uslichen Alten- und Krankenpflege, mit \u00e4lteren Menschen, Spitex, Krankenpflegepersonal usw. zu tun hat&#8230;<\/p>\n","protected":false},"author":1,"featured_media":235374,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-239040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/239040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=239040"}],"version-history":[{"count":0,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/239040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media\/235374"}],"wp:attachment":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=239040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/categories?post=239040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/tags?post=239040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}