{"id":238575,"date":"2020-06-24T13:10:23","date_gmt":"2020-06-24T11:10:23","guid":{"rendered":"https:\/\/stg.beecare.ch\/?p=238575"},"modified":"2023-05-08T16:00:18","modified_gmt":"2023-05-08T14:00:18","slug":"hallux-valgus-ballenzeh-was-ist-ein-hallux-valgus-behandlungen-und-abhilfen","status":"publish","type":"post","link":"https:\/\/stg.beecare.ch\/de\/news\/hallux-valgus-ballenzeh-was-ist-ein-hallux-valgus-behandlungen-und-abhilfen\/","title":{"rendered":"Hallux valgus (Ballenzeh): Was ist ein Hallux valgus? Behandlungen und Abhilfen"},"content":{"rendered":"<p>Der Hallux valgus ist ein Ph\u00e4nomen, das den ersten Mittelfussknochen betrifft und Ursache von physischen und \u00e4sthetischen Probleme f\u00fcr diejenigen ist, die unter einem Ballenzeh leiden. <strong>Lenni Villena<\/strong>, <strong>dipl. Podologin HF<\/strong> und Inhaberin des Fusspflegestudios <strong>Officina del Piede in Barbengo<\/strong> erl\u00e4utert, worum es sich bei Hallux valgus, oder Ballenzeh, handelt, welches die Ursachen sind und wie diesem Problem vorgebeugt werden kann.<\/p>\n<h2>Was ist ein Hallux valgus?<\/h2>\n<p>\u201eDer Hallux valgus zeigt sich als Fehlstellung des Grosszehs in Richtung der kleineren Zehen.\u201c Auf Knochenebene verschiebt sich dabei der erste Mittelfussknochen medial und das erste Grundglied verschiebt sich seitlich.<\/p>\n<p>Mit der lateralen Verschiebung des Grundglieds kommt es auch zu einer Subluxation der Sehnen des Grosszehbeugers aus ihrer urspr\u00fcnglichen Position zwischen den Sesambeinen, was oft mit Schmerzen im betroffenen Bereich einhergeht. In einigen F\u00e4llen kommt es auch zu Knochenhypertrophie, dem \u201eBallen\u201c.<\/p>\n<p>Dieser kann ger\u00f6tet und geschwollen sein und wird von vielen Betroffenen als un\u00e4sthetisch empfunden.<\/p>\n<h2>Ursachen des Hallux valgus<\/h2>\n<p>\u201e<em>Es gibt verschiedene Ursachen f\u00fcr den Hallux valgus, und oft sind sie nicht einfach erkennbar. Diese Verformung kann in der Familie liegen, d.h. genetisch bedingt sein und somit vererbt werden. Ein zu stark abgesenktes Fussgew\u00f6lbe kann zu einem instabilen Vorderfuss und folglicher Verformung des Grosszehengrundgelenks f\u00fchren.<\/em><\/p>\n<p><em>Zu den weiteren Ursachen f\u00fcr den Hallux valgus geh\u00f6ren: Traumata oder auch ungeeignete Schuhe (insbesondere an der Fussspitze zu enge Schuhe, die den Grosszeh \u00fcber zu lange Zeit in eine unnat\u00fcrliche Position zwingen)<\/em>.\u201c<\/p>\n<h2>Behandlungsm\u00f6glichkeiten und Vorbeugung<\/h2>\n<p>\u201e<em>Bei fr\u00fchzeitiger Behandlung (im Wachstumsalter) oder im Anfangsstadium kann nachts eine Schiene verwendet werden, die einen Gegendruck aus\u00fcbt und so verhindert, dass die Gelenkverformung fortschreitet.<\/em><em> <\/em><\/p>\n<p><em>In fortgeschrittenem Alter und bei \u00e4lteren Menschen haben solche Schienen nicht mehr den gleichen Effekt der Korrektur, k\u00f6nnen jedoch dazu beitragen, dass sich die Verformung nicht noch weiter verschlimmert<\/em>\u201c, so die Podologin.<\/p>\n<p>\u201e<em>Wenn ein Hallux valgus in der Kindheit oder Jugend auftritt, sollte ein Spezialist (ein Podologe oder Orthop\u00e4de) hinzugezogen und eine gr\u00fcndliche Untersuchung der Morphologie und der Biomechanik des Fusses vorgenommen werden, da es sehr wichtig ist, rechtzeitig die Ursachen f\u00fcr dieses Problem festzustellen und zu beheben. Eine Operation kann als mikrochirurgischer und somit wenig invasiver Eingriff durchgef\u00fchrt werden.<\/em><\/p>\n<p><em>Der Krankenhausaufenthalt und die Rehabilitation kann in einigen F\u00e4llen bis zu 6 Monaten dauern und in der anf\u00e4nglichen Zeit muss ein postoperativer orthop\u00e4discher Schuh getragen werden.<\/em><\/p>\n<p><em>Die R\u00fcckfallquote bel\u00e4uft sich bis auf 50 Prozent, was bedeutet, dass sich bei der H\u00e4lfte der F\u00e4lle der Hallux valgus neu bilden kann. Dies kann vorkommen, wenn bei der Behandlung und einem Eingriff nicht die eigentlichen Ursachen behoben werden, die zur Fehlstellung und Verformung f\u00fchren (ungeeignete Schuhe, muskuloskelettale Kompensationen etc.), und auch nach dem Eingriff fortbestehen.<\/em><\/p>\n<p><em>Vor einer Behandlung sollte mit dem Orthop\u00e4diechirurgen sorgf\u00e4ltig erwogen werden, ob die Behandlung dem Alter, Lebensstil und den pers\u00f6nlichen Bed\u00fcrfnissen gerecht wird<\/em>.\u201c<\/p>\n<p>Welche M\u00f6glichkeiten stehen den Betroffenen zur Verf\u00fcgung, die einen chirurgischen Eingriff vermeiden m\u00f6chten?<\/p>\n<p>\u201e<em>Als weniger invasive Methoden k\u00f6nnen Silikonorthesen im ersten Zehenzwischenraum eingesetzt werden: In weniger schweren F\u00e4llen, um eine st\u00e4rkere Fehlstellung des Grundglieds zu verhindern, und f\u00fcr komplexere F\u00e4lle, um den Grosszeh vom zweiten Zeh und umgekehrt zu trennen und Probleme durch Reibung der beiden Zehen (Schwielen, Verformungen des zweiten Zehs durch \u00dcberlagerung des Grosszehs, Aufl\u00f6sen und Abtrennen des Zehennagels durch \u00dcberlagerung von Grosszeh und Nagel des zweiten Zehs).<\/em><\/p>\n<p><em>Mit massgeschneiderten Silikonorthesen kann auch der \u201eBallen\u201c vor \u00fcberm\u00e4ssigem Druck durch die Schuhe gesch\u00fctzt werden<\/em>\u201c, erl\u00e4utert <strong>Lenni Villena<\/strong>.<\/p>\n<p>\u201e<em>In einigen F\u00e4llen kann eine orthop\u00e4dische Einlage notwendig sein, um einem Kompensationsverhalten des Fusses vorzubeugen, das die Muskeln ungleichm\u00e4ssig arbeiten l\u00e4sst und die Verformungen verst\u00e4rkt. Entsprechende Kontrollen und Untersuchungen sind immer von einem Podologen oder einer orthop\u00e4dischen Fachkraft vorzunehmen.<\/em><\/p>\n<p><em>In jedem Fall empfiehlt sich als Vorbeugung eines Hallux valgus oder zu Vermeidung einer Verschlimmerung, stets geeignete Schuhe mit einer Form zu w\u00e4hlen, die den Fuss und die Zehen, insbesondere den Grosszeh, nicht in eine unnat\u00fcrliche Haltung zwingen. Die so beliebten hohen Abs\u00e4tze beg\u00fcnstigen dieses Problem.<\/em><\/p>\n<p><em>Ausserdem werden Massagen und ein Bewegungstraining des Fusses empfohlen, um die Gelenke elastisch und einwandfrei funktionsf\u00e4hig zu halten. Die Untersuchung durch einen Spezialisten kann helfen, so weit wie m\u00f6glich die Ursachen f\u00fcr das Auftreten des Hallux valgus festzustellen und die Abhilfen zu erw\u00e4gen, die sich bei den bereits schwereren F\u00e4llen empfehlen oder wenn auch die anderen Zehen betroffen sind<\/em>\u201c, schliesst <strong>Podologin Lenni Villena<\/strong> ab.<\/p>\n<p>Weitere Informationen:<br \/>Fusspflegestudio<br \/>OFFICINA DEL PIEDE<br \/>Via Cantonale 6<br \/>6917 Barbengo<\/p>\n<h2>Video: So bildet sich ein Hallux valgus<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Der Hallux valgus ist ein Ph\u00e4nomen, das den ersten Mittelfussknochen betrifft und Ursache von physischen und \u00e4sthetischen Probleme f\u00fcr diejenigen ist, die unter einem Ballenzeh leiden. <\/p>\n","protected":false},"author":1,"featured_media":237961,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-238575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/238575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=238575"}],"version-history":[{"count":0,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/238575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media\/237961"}],"wp:attachment":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=238575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/categories?post=238575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/tags?post=238575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}