{"id":238273,"date":"2020-03-10T11:13:12","date_gmt":"2020-03-10T09:13:12","guid":{"rendered":"https:\/\/stg.beecare.ch\/news\/scarpe-ortopediche-per-anziani-la-salute-inizia-dai-piedi\/"},"modified":"2023-05-08T16:00:20","modified_gmt":"2023-05-08T14:00:20","slug":"orthopadische-schuhe-fur-altere-menschen-gesundheit-beginnt-bei-den-fusen","status":"publish","type":"post","link":"https:\/\/stg.beecare.ch\/de\/news\/orthopadische-schuhe-fur-altere-menschen-gesundheit-beginnt-bei-den-fusen\/","title":{"rendered":"Orthop\u00e4dische Schuhe f\u00fcr \u00e4ltere Menschen: Gesundheit beginnt bei den F\u00fc\u00dfen"},"content":{"rendered":"<\/p>\n<p>Die besten Bedingungen daf\u00fcr zu schaffen, beim Laufen eine korrekte Haltung einzunehmen, und dabei auch an das Wohlbefinden der F\u00fc\u00dfe zu denken, ist sicherlich eine gro\u00dfe Hilfe f\u00fcr die Gesundheit von \u00e4lteren Menschen insgesamt.<\/p>\n<p>\u201e<em>Unsere F\u00fc\u00dfe sind von gr\u00f6\u00dfter Bedeutung daf\u00fcr, wie wir in unserem Umfeld leben: Wenn die F\u00fc\u00dfe nicht gesund sind, spiegelt sich das auch an unserer Haltung wider<\/em>\u201c, erl\u00e4utert<strong> Lenni Villena, Fu\u00dfpflegerin in Lugano<\/strong>. Wir haben sie darum geben, zu erkl\u00e4ren, wann \u00e4ltere Menschen orthop\u00e4dische Schuhe tragen sollten und was beim Kauf solcher Schuhe zu beachten ist.<\/p>\n<h2>So wichtig sind unsere F\u00fc\u00dfe<\/h2>\n<p>\u201e<em>Bei \u00e4lteren Menschen k\u00f6nnen Fu\u00dfschmerzen eine Belastung im Alltag bedeuten und dazu f\u00fchren, dass der oder die Betroffene das Interesse auch an ganz banalen Dingen verliert\u201c<\/em>, erl\u00e4utert die Fu\u00dfpflegerin. \u201e<em>Die Gesundheit der F\u00fc\u00dfe ist wichtig f\u00fcr die Selbstst\u00e4ndigkeit gerade \u00e4lterer Menschen und verhindert dar\u00fcber hinaus weitere nachteilige Folgen durch ein falsches Aufsetzen der F\u00fc\u00dfe, darunter auch St\u00fcrze und die entsprechenden Komplikationen<\/em>.\u201c<\/p>\n<p>\u201e<em>Zu den h\u00e4ufigsten Fu\u00dfproblemen bei \u00e4lteren Menschen geh\u00f6ren Verformungen (\u00fcbereinanderliegende Zehen, Krallenzehen, Ballenzehen, Spreizfu\u00df), Arthrose, reduziertes Fettgewebe, Schwielen, Hautpilz und Nagelpilz, starke Trockenheit der Haut, nicht ordnungsgem\u00e4\u00df behandelte Verletzungen usw.<\/em><\/p>\n<p><em>Es ist daher wichtig, Schuhe zu tragen, die dem jeweiligen Fu\u00df und auch dem Lebensstil der Person entsprechen<\/em>.\u201c<\/p>\n<h3>Warum sollten \u00e4ltere Menschen orthop\u00e4dische Schuhe tragen?<\/h3>\n<p>Der Begriff orthop\u00e4dische Schuhe bezeichnet verschiedene Arten von Schuhen: von solchen, die nach einer Operation getragen werden, bis hin zu Schuhen f\u00fcr Diabetikerf\u00fc\u00dfe und Pantoffeln f\u00fcr Senioren.<\/p>\n<p>Hier konzentrieren wir uns insbesondere auf zwei Kategorien: ma\u00dfgeschneiderte und in Serie gefertigte orthop\u00e4dische Schuhe.<\/p>\n<p><strong>Lenni Villena<\/strong>: \u201e<em>Ma\u00dfgeschneiderte Schuhe werden auf Anfrage des Patienten angefertigt, der besondere Anforderungen hat und dessen Fu\u00df und Kn\u00f6chel besonders gest\u00fctzt werden m\u00fcssen, was mit einem normalen Schuh nicht m\u00f6glich ist. Verschiedene Pathologien k\u00f6nnen ma\u00dfgeschneiderte Schuhe erfordern, darunter beispielsweise Poliomyelitis, schwere Verletzungen, Folgen von Schlaganfall, motorische und muskul\u00e4re Defizite<\/em>.\u201c<\/p>\n<p>\u201e<em>Serienm\u00e4\u00dfig gefertigte orthop\u00e4dische Schuhe dagegen sind nicht speziell f\u00fcr eine bestimmte Person gedacht. Sie sind allgemein als St\u00fctze und zum Schutz des Fu\u00dfes und f\u00fcr bestimmte Verformungen ausgelegt und bieten eine gr\u00f6\u00dfere Stabilit\u00e4t.<\/em><\/p>\n<p><em>Zu ihren Merkmalen geh\u00f6ren ein weiches und geschmeidiges Obermaterial, das Probleme durch Reiben wie Schwielen, Blasen und Geschw\u00fcre vermeidet. Auch Schmerzen durch zu gro\u00dfen Druck auf die Knochen werden mit diesen Schuhen vermieden, da oft keine internen N\u00e4hte vorhanden sind.<\/em><\/p>\n<p><em>Die Schuhsohlen sind breit und stabil und bieten somit ein besseres Gleichgewicht, was wiederum St\u00fcrzen vorbeugt. Orthop\u00e4dische Schuhe lassen sich leicht schn\u00fcren und sind auch aus diesem Grund sehr praktisch<\/em>.\u201c<\/p>\n<p>Es gibt eine gro\u00dfe Auswahl von orthop\u00e4dischen Schuhen, die zum Teil auch sehr technisch sind. Man sollte sich daher von einem Experten beraten lassen \u2013 einem Fu\u00dfpfleger, einem Orthop\u00e4den oder einem Fachgesch\u00e4ft.<\/p>\n<p>Orthop\u00e4dische Schuhe werden nicht in den Schuhabteilungen gro\u00dfer Kaufh\u00e4user verkauft, sondern in speziellen Fachgesch\u00e4ften und Sanit\u00e4tsh\u00e4usern. Auf Anfrage kann sie eventuell auch der Fu\u00dfpfleger zur Verf\u00fcgung stellen.<\/p>\n<h2>Welche orthop\u00e4dischen Schuhe sollten \u00e4ltere Menschen kaufen?<\/h2>\n<p>Bei der Auswahl des richtigen Schuhs sollte immer auf bestimmte Eigenschaften geachtet werden, erkl\u00e4rt die Fu\u00dfpflegerin. \u201e<em>In erster Linie Breite und L\u00e4nge der F\u00fc\u00dfe: Hierzu sollte man die Fu\u00dfsohle herausnehmen und sich (m\u00f6glichst mit gebeugten Knien) daraufstellen. In dieser Position muss die Fu\u00dfsohle mindestens 1 cm l\u00e4nger als die l\u00e4ngste Zehe sein und die Breite muss mindestens der Breite des Fu\u00dfes entsprechen (und darf auf keinen Fall schmaler sein!).<\/em><\/p>\n<p><em>Das scheint banal, aber ein bequemer Schuh bedeutet nicht einfach, das die Gr\u00f6\u00dfe stimmt<\/em>.\u201c<\/p>\n<p><em>\u201c<\/em><em>Der Schaft muss hoch sein und darf die Zehen nicht einquetschen.. Das Material sollte m\u00f6glichst weich sein. Die Schuhe m\u00fcssen sich auf dem Fu\u00dfr\u00fccken schn\u00fcren lassen. Die Hinterkappe (an der Ferse) darf nicht nachgeben, sondern muss steif sein, um den Fu\u00df zu stabilisieren.\u201c<\/em><\/p>\n<p>Was die Schuhsohlen betrifft, empfiehlt die Fu\u00dfpflegerin breite und stabile Sohlen.<\/p>\n<p>Wenn ein Absatz unbedingt sein muss, sollte er h\u00f6chsten 5 cm hoch sein!<\/p>\n<p><strong>Weitere Informationen: +41 (0)76 403 04 44<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die besten Bedingungen daf\u00fcr zu schaffen, beim Laufen eine korrekte Haltung einzunehmen, und dabei auch an das Wohlbefinden der F\u00fc\u00dfe zu denken, ist sicherlich eine gro\u00dfe Hilfe f\u00fcr die Gesundheit von \u00e4lteren Menschen insgesamt.<\/p>\n","protected":false},"author":1,"featured_media":237325,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-238273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/238273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=238273"}],"version-history":[{"count":0,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/238273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media\/237325"}],"wp:attachment":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=238273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/categories?post=238273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/tags?post=238273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}