{"id":238206,"date":"2020-04-20T14:12:16","date_gmt":"2020-04-20T12:12:16","guid":{"rendered":"https:\/\/stg.beecare.ch\/news\/coronavirus-aiuto-psicologico-per-gli-anziani\/"},"modified":"2023-05-08T16:00:19","modified_gmt":"2023-05-08T14:00:19","slug":"coronavirus-so-konnen-wir-unseren-angehorigen-psychologisch-helfen","status":"publish","type":"post","link":"https:\/\/stg.beecare.ch\/de\/news\/coronavirus-so-konnen-wir-unseren-angehorigen-psychologisch-helfen\/","title":{"rendered":"Coronavirus: So k\u00f6nnen wir unseren Angeh\u00f6rigen psychologisch helfen"},"content":{"rendered":"<\/p>\n<p>\u00c4ltere Menschen in der <a href=\"https:\/\/stg.beecare.ch\/de\/news\/coronavirus-und-altere-menschen-symptome-und-wie-man-damit-umgeht\/\"><strong>Coronavirus-Krise<\/strong><\/a>: Aufgrund der aktuellen Ausnahmesituation k\u00f6nnen viele Senioren ihre Wohnung oder ihr Haus nicht verlassen \u2013 nicht einmal, um einkaufen zu gehen.<\/p>\n<p>Wie f\u00fcr alle ist es auch f\u00fcr sie ein gro\u00dfes Opfer, zu Hause zu bleiben, das viele Emotionen und aus psychologischer Sicht nicht wenige Schwierigkeiten aufkommen l\u00e4sst.<\/p>\n<p>Um Klarheit \u00fcber die Umst\u00e4nde zu schaffen und auch ein paar praktische Ratschl\u00e4ge dar\u00fcber einzuholen, wie man \u00e4lteren Menschen helfen kann, die momentan in Isolation zu Hause leben, haben wir mit Carla Faggioli, Psychologin und Psychotherapeutin bei der FSP in Lugano, gesprochen.<\/p>\n<h2>\u00c4ltere Menschen in Isolation zu Hause: ein Bruch des gewohnten Schemas<\/h2>\n<p>\u201e<em>Wir befinden uns gerade in einer au\u00dferordentlichen und einzigartigen Situation, die unseren Alltag und unsere gewohnte Routine komplett durcheinanderbringt und es unm\u00f6glich macht, den Gewohnheiten nachzugehen, die f\u00fcr \u00e4ltere Menschen oft das sind, was ihnen Sicherheit und Stabilit\u00e4t gibt. <\/em><\/p>\n<p><em>Wir haben den Eindruck, unseren Alltag mit unseren Gewohnheiten unter Kontrolle zu halten. Jetzt ist es so, als habe ein Tsunami alles an die Oberfl\u00e4che gebracht, was tief unten geschlummert hatte: Instabilit\u00e4t und Verletzbarkeit. Wir sind daher gezwungen, innerhalb von kurzer Zeit ein neues Schema mit Gewohnheiten zu schaffen, da wir anderenfalls ein Gef\u00fchl von Unsicherheit und Angst haben.<\/em><\/p>\n<p><em>In diesem Moment k\u00f6nnen Aspekte zutage kommen, die wir im Laufe der Jahre nicht sehen wollten oder die wir nicht kompensiert haben. Aus diesem Grund kommt auch das Bild, das wir von uns hatten, durcheinander. Eine solche Situation ruft zwei Reaktionen hervor: Einige werden aufgrund von Frustration wesentlich aggressiver, andere wiederum depressiv und niedergeschlagen aufgrund der M\u00fche, die die Umst\u00e4nde mit sich bringen. <\/em><\/p>\n<p><em>Dies gilt auch f\u00fcr Menschen in fortgeschrittenem Alter, die in Isolation zu Hause leben, und insbesondere f\u00fcr diejenigen, die bereits besonders verletzlich und eingeschr\u00e4nkt sind.<\/em>\u201c<\/p>\n<h2>Emotionen von \u00e4lteren Menschen in Isolation zu Hause: Angst<\/h2>\n<p>\u201e<em>Dieser durch das Coronavirus ausgel\u00f6ste Tsunami f\u00f6rdert Gedanken und Erinnerungen zutage, die sich darauf auswirken, wie wir das wahrnehmen, was um uns geschieht. Viele \u00e4ltere Menschen haben Angst und fragen sich: Was wird mit mir? Wir wird das enden? In diesem Moment ist an vielen H\u00e4usern ein Regenbogen und der Satz \u201e<\/em><\/p>\n<p>Alles wird gut<em>\u201c zu sehen \u2013 ein Ausdruck der Bev\u00f6lkerung, der das Bed\u00fcrfnis ausdr\u00fcckt, uns gegenseitig zu unterst\u00fctzen. Um die Angst unter Kontrolle zu halten, muss dieser Spruch jedoch durch den Verweis auf konkrete Handlungen erg\u00e4nzt werden.\u201c<\/em><\/p>\n<p>Mit anderen Worten: Alles wird gut, weil ich zu Hause bleibe. Alles wird gut, weil ich mir die H\u00e4nde wasche. Alles wird gut, weil ich die soziale Distanz halte. Dr. Faggioli hebt hervor: <em>\u201eWir m\u00fcssen auch Informationen liefern, die eine konkrete Grundlage daf\u00fcr geben, dass alles gut wird<\/em>.\u201c<\/p>\n<h2>Emotionen von \u00e4lteren Menschen in Isolation zu Hause: Freude<\/h2>\n<p>\u201e<em>F\u00fcr in Isolation lebende \u00e4ltere Menschen ist es in diesem Moment auch wichtig, sich freuen zu k\u00f6nnen, zu wissen, dass es etwas gibt, wor\u00fcber sie sich freuen k\u00f6nnen. Eine meiner Patientinnen beispielsweise freut sich und ist gl\u00fccklich dar\u00fcber, dass ihre Kinder f\u00fcr sie einkaufen und sie h\u00e4ufiger anrufen. Viele Kinder k\u00fcmmern sich mehr um ihre \u00e4lteren Eltern, was diese gl\u00fccklich macht.<\/em>\u201c<\/p>\n<p>Nat\u00fcrlich kann man nicht davon ausgehen, dass eine Person und auch \u00e4ltere Menschen den ganzen Tag Freude empfinden.<\/p>\n<p>\u201e<em>Es ist wichtig, die eigenen Emotionen anzunehmen, die auch von einer Stunde zur anderen variieren k\u00f6nnen<\/em>\u201c, r\u00e4t die Psychologin aus Lugano.<\/p>\n<p>\u201e<em>Wir m\u00fcssen lernen, uns selbst Gesellschaft zu leisten. Au\u00dferdem muss man die Geschehnisse aus einer kreativen Perspektive betrachten, d.h. auch das Sch\u00f6ne und die positiven Seiten an der Situation sehen.<\/em>\u201c<\/p>\n<h2>Emotionen von \u00e4lteren Menschen in Isolation zu Hause: Wut<\/h2>\n<p>\u201e<em>Viele \u00e4ltere Menschen, die derzeit in Isolation zu Hause leben, riskieren, sich in eine Wut zu steigern, die \u00fcber ihren eigentlichen Willen hinausgeht. Sie konnten immer frei ausgehen und andere Menschen treffen, und nun ist es ihnen sogar untersagt, einkaufen zu gehen. Ein solches Verbot kann auch zu gro\u00dfer Wut f\u00fchren, wenn man die zugrunde liegende Motivation nicht akzeptiert: dass das eigene Zuhause in diesem Moment Schutz bietet. <\/em><\/p>\n<p><em>Es ist nicht einfach, diesen Aspekt verst\u00e4ndlich zu machen. Man kann ihn jedoch verdeutlichen, indem man den \u00e4lteren Menschen in Erinnerung ruft, wie es war, als ihre Kinder noch klein waren. Wie oft haben sie ihren Kindern Anweisungen gegeben, die nur f\u00fcr ihr Bestes waren?<\/em><\/p>\n<p><em>Ein Verbot f\u00fcr ein Kind wie beispielsweise, nicht mit Messern zu spielen, dient objektiv zu seinem Schutz. Und selbst, wenn das Kind weinend um das Messer bittet, wird es ihm trotzdem nicht gegeben. Dieses Beispiel verdeutlicht \u00e4lteren Menschen, dass die Emotionen, die sie gerade durchleben, nur eine nat\u00fcrliche Folge von Frustration und einem Gef\u00fchl der Hilflosigkeit sind. <\/em><\/p>\n<p><em>Man kann den \u00e4lteren Menschen verst\u00e4ndlich machen, dass die \u00c4rzte Dinge wissen, die wir nicht wissen und auch nicht sehen und somit erkennen k\u00f6nnen. Man braucht Zeit, um die Wut zu verstehen, um sie zu akzeptieren und anzunehmen und schlie\u00dflich zu verdauen.<\/em>\u201c<\/p>\n<h2>Emotionen von \u00e4lteren Menschen in Isolation zu Hause: Traurigkeit<\/h2>\n<p>\u201e<em>Um zum Beispiel des Spruchs \u201eAlles wird gut\u201c zur\u00fcckzukommen: Wir m\u00fcssen gerade die \u00e4lteren Menschen auch daran erinnern, dass alles gut wird, weil sie nicht allein sind. Den zu Hause in Isolation lebenden Senioren m\u00fcssen wir ins Ged\u00e4chtnis rufen, dass sich der Staat und die Angeh\u00f6rigen um sie k\u00fcmmern, und das auch in Form von Verboten. Und wir haben die Gelegenheit \u00fcber Dinge nachzudenken, die nicht gut laufen, aber gut laufen k\u00f6nnen. Es gibt zum Beispiel \u00e4ltere Menschen, die den Kontakt zu ihren Verwandten abgebrochen haben. <\/em><\/p>\n<p><em>Und die aktuelle Situation kann eine Gelegenheit sein, diese Beziehungen wieder aufleben zu lassen. Die Bed\u00fcrfnisse, die in mir aufkommen, k\u00f6nnen in dem Ma\u00dfe alles zum Guten wenden, in dem ich mich frage: Was kann ich tun?<\/em>\u201d<\/p>\n<h2>Emotionen von \u00e4lteren Menschen in Isolation zu Hause: Depression<\/h2>\n<p>\u201e<em>Traurigkeit ist auch ein Gef\u00fchl des Verlusts: Etwas f\u00fcr uns Wichtiges ist verloren gegangen. Wir m\u00fcssen immer daran denken, dass diese au\u00dferordentliche Situation zeitlich begrenzt ist. Es hilft, Grenzen zu setzen, wenn man sich in Erinnerung ruft, dass sie ein Ende haben wird. Es ist normal, dass zu Hause in Isolation lebende \u00e4ltere Menschen depressiv sind, da sie vor\u00fcbergehend bestimmte Dinge nicht mehr haben. Diese Personen m\u00fcssen daran erinnert werden, dass die Sonne hinter den Wolken wartet.<\/em>\u201c<\/p>\n<p><strong>Wir k\u00f6nnen wir konkret Menschen helfen, die aufgrund des Coronavirus zu Hause in Isolation leben m\u00fcssen und deswegen eine Depression entwickelt haben?<\/strong><\/p>\n<p>\u201e<em>Wenn man etwas verloren hat, ist es wichtig, dabei zu helfen, die Leere zu f\u00fcllen und die Kreativit\u00e4t zu f\u00f6rdern\u201c<\/em>, erkl\u00e4rt die <strong>Psychologin und Psychotherapeutin Carla Faggioli<\/strong>. <em>\u201eAlles, was in irgendeiner Form kreativ ist, bek\u00e4mpft das Gef\u00fchl von Hilflosigkeit und Niedergeschlagenheit. Die \u00e4lteren Menschen zu Hause, und nicht nur sie, m\u00fcssen sich in dieser Situation die Frage stellen: Worin bin ich gut? Zum Beispiel im Malen, Kochen, Basteln, Schreiben&#8230; und es dann auch tun.<\/em><\/p>\n<p><em>F\u00fcr \u00e4ltere Menschen ist es au\u00dferdem wichtig, sich an die Vergangenheit zu erinnern und davon zu erz\u00e4hlen (auch am Telefon). Auch das kann aus der Depression helfen und ihnen bewusst machen, dass sie anderen noch etwas geben k\u00f6nnen. Ebenfalls helfen kann in diesem Moment, davon zu tr\u00e4umen, was man nach Ende dieser Phase macht. Dies sind Ratschl\u00e4ge, um diese Situation etwas zu erleichtern und sich selbst Gesellschaft zu leisten \u2013 in einem Gem\u00fctszustand, der nicht unterdr\u00fcckt, sondern angenommen und begleitet werden muss.<\/em>\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c4ltere Menschen in der Coronavirus-Krise: Aufgrund der aktuellen Ausnahmesituation k\u00f6nnen viele Senioren ihre Wohnung oder ihr Haus nicht verlassen \u2013 nicht einmal, um einkaufen zu gehen.<\/p>\n","protected":false},"author":1,"featured_media":237439,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-238206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/238206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=238206"}],"version-history":[{"count":0,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/238206\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media\/237439"}],"wp:attachment":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=238206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/categories?post=238206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/tags?post=238206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}