{"id":237902,"date":"2019-01-21T15:12:52","date_gmt":"2019-01-21T13:12:52","guid":{"rendered":"https:\/\/stg.beecare.ch\/news\/aspettativa-di-vita-che-cosa-ci-fa-vivere-meglio\/"},"modified":"2023-05-08T16:00:32","modified_gmt":"2023-05-08T14:00:32","slug":"lebenserwartung-was-tragt-zu-einer-besseren-lebensqualitat-bei","status":"publish","type":"post","link":"https:\/\/stg.beecare.ch\/de\/news\/lebenserwartung-was-tragt-zu-einer-besseren-lebensqualitat-bei\/","title":{"rendered":"Lebenserwartung: Was tr\u00e4gt zu einer besseren Lebensqualit\u00e4t bei?"},"content":{"rendered":"<p>Das <strong>Institute for Health Metrics and Evaluation<\/strong> hat in der Zeitschrift Lancet seine j\u00fcngste Studie in Bezug auf die Lebenserwartung und die h\u00e4ufigsten Todesursachen von heute bis zum Jahre 2040 ver\u00f6ffentlicht und dabei verschiedene Szenarien ber\u00fccksichtigt.<\/p>\n<p>Die g\u00fcnstigsten Szenarien gehen von einer leicht h\u00f6heren Lebenserwartung aus, allerdings sind nicht alle Vorhersagen so optimistisch. Nach den g\u00fcnstigsten Szenarien wird sich die Lebenserwartung von heute bis 2040 in circa 50 L\u00e4ndern um 10 Jahre verl\u00e4ngern. Das pessimistischste Szenario geht davon aus, dass sich in mindestens der H\u00e4lfte der L\u00e4nder die Lebenserwartung gegen\u00fcber dem heutigen Stand verringert.<\/p>\n<p>\u201e<em>Die Zukunft der Gesundheit in der Welt <\/em>\u201c, so der Hauptautor der Studie, Kyle Foreman, Director of Data Science in Institute for Health Metrics and Evaluation (IHME) der University of Washington,<em> \u201eist nicht festgelegt und kann sich unterschiedlich entwickeln. Der Fortschritt oder die Stagnation h\u00e4ngen davon ab, wie gut oder schlecht sich die Gesundheitssysteme mit den wichtigsten Gesundheitsfaktoren befassen.<\/em>\u201c<\/p>\n<p>Die Top Ten der Lebenserwartung im Jahre 2040<\/p>\n<ol>\n<li><strong>Spanien (85,8 Jahre) <\/strong>\u2013 2016 belegte das Land Platz 4 mit einer Lebenserwartung von 82,9 Jahren<\/li>\n<li><strong>Japan (85,7 Jahre) <\/strong>\u2013 2016 belegte das Land Platz 1 mit einer Lebenserwartung von 83,7 Jahren<\/li>\n<li><strong>Singapur (85,4 Jahre) <\/strong>\u2013 2016 belegte das Land Platz 3 mit einer Lebenserwartung von 83,3 Jahren<\/li>\n<li><strong>Schweiz (85,2 Jahre) <\/strong>\u2013 2016 belegte das Land Platz 2 mit einer Lebenserwartung von 83,3 Jahren<\/li>\n<li><strong>Portugal (84,5 Jahre) <\/strong>\u2013 2016 belegte das Land Platz 23 mit einer Lebenserwartung von 81 Jahren<\/li>\n<li><strong>Italien (84,5 Jahre) <\/strong>\u2013 2016 belegte das Land Platz 7 mit einer Lebenserwartung von 82,3 Jahren<\/li>\n<li><strong>Israel (84,4 Jahre) <\/strong>\u2013 2016 belegte das Land Platz 13 mit einer Lebenserwartung von 82,1 Jahren<\/li>\n<li><strong>Frankreich (84,3 Jahre) <\/strong>\u2013 2016 belegte das Land Platz 8 mit einer Lebenserwartung von 82,3 Jahren<\/li>\n<li><strong>Luxemburg (84,1 Jahre) <\/strong>\u2013 2016 belegte das Land Platz 10 mit einer Lebenserwartung von 82,2 Jahren<\/li>\n<li><strong>Australien (84,1 Jahre) <\/strong>\u2013 2016 belegte das Land Platz 5 mit einer Lebenserwartung von 82,5 Jahren<\/li>\n<\/ol>\n<p>Die Lekt\u00fcre dieser Studie, die wir im Internet gefunden haben, dient uns angesichts der Aussagen des Leiters des IHME als Denkanreiz.<\/p>\n<p>Besondere Aufmerksamkeit verdient der Satz \u201e<em>Der Fortschritt oder die Stagnation h\u00e4ngen davon ab, wie gut oder schlecht sich die Gesundheitssysteme mit den wichtigsten Gesundheitsfaktoren befassen<\/em>.\u201c<\/p>\n<p>Was bedeutet dieser Satz f\u00fcr all diejenigen, die Spitex-Dienste f\u00fcr die h\u00e4usliche Pflege bieten, und insbesondere f\u00fcr BeeCare?<\/p>\n<p>F\u00fcr uns bei <strong>BeeCare<\/strong> bedeutet er, dass der Pflegedienst eine immer wichtigere Rollen spielen wird, da die Menschen mit steigendem Alter mehr Hilfe und Unterst\u00fctzung ben\u00f6tigen.<\/p>\n<p>In diesem Kontext haben das Krankenpflegepersonal, Gesundheitspfleger\/innen, Pflegehelfer\/innen, Betreuer\/innen oder Mitarbeiter\/innen f\u00fcr Hauswirtschaft bei BeeCare die anspruchsvolle Aufgabe, den Familien als Hilfe beiseite zu stehen, d.h. ein Ansprechpartner f\u00fcr all das zu sein oder zu werden, was die h\u00e4usliche Alten- und Krankenpflege betrifft.<\/p>\n<p>Die Philosophie und die Methode, auf der unsere Arbeit basiert, gr\u00fcndet auf einer Aussage von Florence Nightingale:<\/p>\n<p>\u201e<em>Krankenpflege ist eine Kunst und fordert, wenn sie Kunst werden soll, eine ebenso gro\u00dfe Hingabe, eine ebenso gro\u00dfe Vorbereitung, wie das Werk eines Malers oder Bildhauers. Denn was bedeutet die Arbeit an toter Leinwand oder kaltem Marmor im Vergleich zu der am lebendigen K\u00f6rper, dem Tempel f\u00fcr den Geist Gottes? Sie ist eine der Sch\u00f6nen K\u00fcnste. Die sch\u00f6nste der Sch\u00f6nen K\u00fcnste.<\/em>\u201c<\/p>\n<p>Nur mit dieser Vision der h\u00e4uslichen Pflege kann ein guter Pflegedienst garantiert werden.<\/p>\n<h2>Spitex-Dienst: h\u00e4usliche Alten- und Krankenpflege<\/h2>\n<p>Die <a href=\"\/de\/unsere-leistungen\/\"><strong>Hilfe und Pflege zu Hause<\/strong><\/a>, oder <strong>Spitex<\/strong>, muss auf dieser Philosophie basieren.<\/p>\n<p>Die beruflichen T\u00e4tigkeiten im Rahmen der Spitex-Leistungen m\u00fcssen durch eine positive Vision der Person gest\u00fctzt werden. Um unsere Arbeit gut machen zu k\u00f6nnen, m\u00fcssen beide Aspekte ineinandergreifen. Unsere Erfahrung zeigt, dass der menschliche Aspekt den beruflichen Aspekt weit \u00fcbertrifft.<\/p>\n<p>Es reicht nicht aus, der alten Dame, die wir betreuen, ihre Str\u00fcmpfe richtig anzuziehen. Heutzutage m\u00f6chten diese Menschen betreut werden, sie m\u00f6chten gefragt werden, ob es ihnen gut geht, sie m\u00f6chten wissen, ob wir sie m\u00f6gen.<\/p>\n<p>Wenn alle <strong>Spitex-Dienste<\/strong> wieder nach dieser Philosophie arbeiten, k\u00f6nnen wir auch der Entwicklung der Lebenserwartung ruhig entgegensehen und korrekt damit umgehen.<\/p>\n<p>Die wachsende Zahl an pflegebed\u00fcrftigen Personen muss ein Denkansto\u00df f\u00fcr die Anbieter von h\u00e4uslichen Pflegedienstleistungen sein, um eine stets hochwertige Qualit\u00e4t und einen menschlichen Ansatz bei der Erbringung dieses Dienstes zu bieten.<\/p>\n<p>Wenn wir dies aus den Augen verlieren, leben die betreuten Menschen auch bis zu 100 Jahren, ohne wirklich den Unterschied zu bemerken.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Institute for Health Metrics and Evaluation hat in der Zeitschrift Lancet seine j\u00fcngste Studie in Bezug auf die Lebenserwartung und die h\u00e4ufigsten Todesursachen von heute bis zum Jahre 2040 ver\u00f6ffentlicht und dabei verschiedene Szenarien ber\u00fccksichtigt.<\/p>\n","protected":false},"author":1,"featured_media":235366,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_mbp_gutenberg_autopost":false,"_pgmb_is_evergreen":true,"_pgmb_ap_template_id":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-237902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/237902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/comments?post=237902"}],"version-history":[{"count":0,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/posts\/237902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media\/235366"}],"wp:attachment":[{"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/media?parent=237902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/categories?post=237902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.beecare.ch\/de\/wp-json\/wp\/v2\/tags?post=237902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}